{"id":26,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/category\/rap\/anglais\/","name":"anglais","slug":"anglais","taxonomy":"category","parent":5,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/zbercegeay\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}