{"id":635,"date":"2025-01-21T23:36:08","date_gmt":"2025-01-21T22:36:08","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/?p=635"},"modified":"2026-03-31T23:13:11","modified_gmt":"2026-03-31T21:13:11","slug":"ikea-a-la-nuit-tombee","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/","title":{"rendered":"Ikea \u00e0 la nuit tomb\u00e9e"},"content":{"rendered":"\n<p style=\"font-size:16px\">J&rsquo;ai trouv\u00e9 un article publi\u00e9 sur le site <a href=\"https:\/\/jai-un-pote-dans-la.com\/dormir-chez-ikea-quand-le-reve-devient-realite\/\" data-type=\"link\" data-id=\"https:\/\/jai-un-pote-dans-la.com\/dormir-chez-ikea-quand-le-reve-devient-realite\/\">J\u2019ai un pote dans la com<\/a>, r\u00e9dig\u00e9 par Penelope Hubert, le 15 janvier 2025. Ce sujet m\u2019a particuli\u00e8rement int\u00e9ress\u00e9e car en faisant des \u00e9tudes de communication, je trouve fascinant de voir comment une marque peut transformer une id\u00e9e simple en une exp\u00e9rience marquante.<\/p>\n\n\n\n<p style=\"font-size:16px\">Pour moi, c&rsquo;est une initiative qui casse les codes. L\u2019id\u00e9e derri\u00e8re cette campagne est simple mais puissante. Chaque participant peut s&rsquo;installer dans une chambre am\u00e9nag\u00e9e dans les moindres d\u00e9tails pour passer la nuit. Gr\u00e2ce \u00e0 cette d\u00e9marche, IKEA d\u00e9passe son r\u00f4le de simple distributeur de meubles pour se positionner comme une marque proche de ses consommateurs et \u00e0 l\u2019\u00e9coute de leurs r\u00eaves.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Dans cet article, deux th\u00e8mes principaux sont ressorti :<\/p>\n\n\n\n<p style=\"font-size:16px\"><strong>-L\u2019image de marque<\/strong><\/p>\n\n\n\n<p style=\"font-size:16px\"><strong>-La communication \u00e9motionnelle et participative<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading has-large-font-size\"><strong>L\u2019image de marque <\/strong><\/h4>\n\n\n\n<p style=\"font-size:16px\">Derri\u00e8re cela, IKEA souhaite humaniser sa marque. Plut\u00f4t que de se positionner uniquement comme un acteur \u00e9conomique, IKEA veut de devenir une marque \u00e0 part enti\u00e8re dans le quotidien de ses consommateurs. L&rsquo;enseigne cherche \u00e0 s&rsquo;int\u00e9grer \u00e0 des moments de vie plus personnels et plus intimes, \u00e0 travers cette offre hors du commun. Au-del\u00e0 de l\u2019aspect ludique, cette initiative permet \u00e0 IKEA de se rapprocher de ses clients, en les invitant \u00e0 vivre une exp\u00e9rience unique, IKEA parvient \u00e0 cr\u00e9er une connexion. Cela montre \u00e9galement que l&rsquo;entreprise ne se contente pas de vendre des meubles, mais qu\u2019elle s&rsquo;int\u00e9resse au bien-\u00eatre de ses clients et \u00e0 l\u2019ambiance qu\u2019ils cr\u00e9ent chez eux. <\/p>\n\n\n\n<p style=\"font-size:16px\">Cette humanisation de l\u2019image de marque r\u00e9pond \u00e0 une volont\u00e9 plus large des entreprises de se distancer des st\u00e9r\u00e9otypes d\u2019un commerce froid et uniquement ax\u00e9 sur la vente de produits. En effet, cette <a href=\"https:\/\/theses.hal.science\/tel-00524879v1\/file\/These_Ambroise.pdf?utm_source\" data-type=\"link\" data-id=\"https:\/\/theses.hal.science\/tel-00524879v1\/file\/These_Ambroise.pdf?utm_source\">\u00e9tude<\/a> nous dit cela \u00ab\u00a0Il semble que la personnalit\u00e9 soit devenue une facette primordiale de la compr\u00e9hension des marques et de leur relation avec les consommateurs.[..]les dirigeants des entreprises sont convaincus que le succ\u00e8s d&rsquo;une marque tient la proximit\u00e9 que celle-ci sait \u00e9tablir et conserver avec ses consommateurs.\u00a0\u00bb<\/p>\n\n\n\n<p style=\"font-size:16px\"> IKEA incarne cette \u00e9volution vers des pratiques plus humaines et plus proches des attentes soci\u00e9tales actuelles.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading has-large-font-size\"><strong>Une communication \u00e9motionnelle et participative<\/strong><\/h4>\n\n\n\n<p style=\"font-size:16px\">D&rsquo;un point de vue communicationnel, cette campagne est une r\u00e9ussite. IKEA joue sur l&rsquo;\u00e9motion, en offrant aux consommateurs une exp\u00e9rience marquante et personnelle. Gr\u00e2ce \u00e0 cette initiative, la marque cr\u00e9e un lien plus fort avec son public. Plut\u00f4t que de simplement diffuser des messages commerciaux, IKEA devient un acteur dans la vie de ses clients, en leur offrant un souvenir qu&rsquo;ils pourront partager et raconter. Dans cet <a href=\"https:\/\/www.affmu.com\/fr\/event-marketing-statistics.html?utm_source\" data-type=\"link\" data-id=\"https:\/\/www.affmu.com\/fr\/event-marketing-statistics.html?utm_source\">article<\/a> ont le constate avec les statistiques suivantes: 73 % des sp\u00e9cialistes du marketing consid\u00e8rent le marketing \u00e9v\u00e9nementiel comme une strat\u00e9gie tr\u00e8s efficace pour promouvoir la notori\u00e9t\u00e9 de la marque et 81% des participants se sentent plus connect\u00e9s \u00e0 une marque apr\u00e8s avoir assist\u00e9 \u00e0 un \u00e9v\u00e9nement.<\/p>\n\n\n\n<p style=\"font-size:16px\">De plus, les participants seront invit\u00e9s \u00e0 partager leurs exp\u00e9riences sur les r\u00e9seaux sociaux, ce qui permettra \u00e0 la marque d\u2019atteindre une audience encore plus large. Ce bouche-\u00e0-oreille num\u00e9rique et les partages de moments personnels favorisent un engagement plus fort et un attachement plus durable.<\/p>\n\n\n\n<p style=\"font-size:13px\">\u00c0 travers cette initiative, IKEA ne se contente pas de vendre un produit, mais cr\u00e9e un lien \u00e9motionnel et humain avec ses clients. En transformant un acte de consommation en un souvenir unique, la marque se positionne comme un acteur cl\u00e9 de la communication responsable et originale. Ce type d\u2019action montre qu\u2019aujourd&rsquo;hui, pour se distinguer, il ne suffit pas de vendre des produits, mais d\u2019enrichir l\u2019exp\u00e9rience du consommateur en y int\u00e9grant des moments de vie et de partage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai trouv\u00e9 un article publi\u00e9 sur le site J\u2019ai un pote dans la com, r\u00e9dig\u00e9 par Penelope Hubert, le 15 janvier 2025. Ce sujet m\u2019a particuli\u00e8rement int\u00e9ress\u00e9e car en faisant des \u00e9tudes de communication, je trouve fascinant de voir comment&#8230; <a class=\"more-link\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-635","post","type-post","status-publish","format-standard","hentry","category-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont\" \/>\n<meta property=\"og:description\" content=\"J&rsquo;ai trouv\u00e9 un article publi\u00e9 sur le site J\u2019ai un pote dans la com, r\u00e9dig\u00e9 par Penelope Hubert, le 15 janvier 2025. Ce sujet m\u2019a particuli\u00e8rement int\u00e9ress\u00e9e car en faisant des \u00e9tudes de communication, je trouve fascinant de voir comment... Continue Reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecrits Num\u00e9riques - Rozenn Dupont\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T22:36:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T21:13:11+00:00\" \/>\n<meta name=\"author\" content=\"rozdupont\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rozdupont\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/\"},\"author\":{\"name\":\"rozdupont\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#\\\/schema\\\/person\\\/c949fa3334c3ce5c0478546af6847f29\"},\"headline\":\"Ikea \u00e0 la nuit tomb\u00e9e\",\"datePublished\":\"2025-01-21T22:36:08+00:00\",\"dateModified\":\"2026-03-31T21:13:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/\"},\"wordCount\":648,\"commentCount\":0,\"articleSection\":[\"Articles Laurent\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/\",\"url\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/\",\"name\":\"Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#website\"},\"datePublished\":\"2025-01-21T22:36:08+00:00\",\"dateModified\":\"2026-03-31T21:13:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#\\\/schema\\\/person\\\/c949fa3334c3ce5c0478546af6847f29\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/2025\\\/01\\\/21\\\/ikea-a-la-nuit-tombee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ikea \u00e0 la nuit tomb\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#website\",\"url\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/\",\"name\":\"Ecrits Num\u00e9riques - Rozenn Dupont\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#\\\/schema\\\/person\\\/c949fa3334c3ce5c0478546af6847f29\",\"name\":\"rozdupont\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g\",\"caption\":\"rozdupont\"},\"sameAs\":[\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\"],\"url\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/author\\\/rozdupont\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont","og_description":"J&rsquo;ai trouv\u00e9 un article publi\u00e9 sur le site J\u2019ai un pote dans la com, r\u00e9dig\u00e9 par Penelope Hubert, le 15 janvier 2025. Ce sujet m\u2019a particuli\u00e8rement int\u00e9ress\u00e9e car en faisant des \u00e9tudes de communication, je trouve fascinant de voir comment... Continue Reading &rarr;","og_url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/","og_site_name":"Ecrits Num\u00e9riques - Rozenn Dupont","article_published_time":"2025-01-21T22:36:08+00:00","article_modified_time":"2026-03-31T21:13:11+00:00","author":"rozdupont","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rozdupont","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/#article","isPartOf":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/"},"author":{"name":"rozdupont","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#\/schema\/person\/c949fa3334c3ce5c0478546af6847f29"},"headline":"Ikea \u00e0 la nuit tomb\u00e9e","datePublished":"2025-01-21T22:36:08+00:00","dateModified":"2026-03-31T21:13:11+00:00","mainEntityOfPage":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/"},"wordCount":648,"commentCount":0,"articleSection":["Articles Laurent"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/","url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/","name":"Ikea \u00e0 la nuit tomb\u00e9e - Ecrits Num\u00e9riques - Rozenn Dupont","isPartOf":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#website"},"datePublished":"2025-01-21T22:36:08+00:00","dateModified":"2026-03-31T21:13:11+00:00","author":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#\/schema\/person\/c949fa3334c3ce5c0478546af6847f29"},"breadcrumb":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/2025\/01\/21\/ikea-a-la-nuit-tombee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/"},{"@type":"ListItem","position":2,"name":"Ikea \u00e0 la nuit tomb\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#website","url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/","name":"Ecrits Num\u00e9riques - Rozenn Dupont","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#\/schema\/person\/c949fa3334c3ce5c0478546af6847f29","name":"rozdupont","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18fb870447c18b80a6a3c1f025e0b13e5bf521acd5191a49c22b02dc7b82899d?s=96&d=mm&r=g","caption":"rozdupont"},"sameAs":["https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont"],"url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/author\/rozdupont\/"}]}},"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/posts\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/comments?post=635"}],"version-history":[{"count":3,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/posts\/635\/revisions"}],"predecessor-version":[{"id":640,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/posts\/635\/revisions\/640"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/media?parent=635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/categories?post=635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/tags?post=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}