{"id":34,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/","name":"Pop anglaise","slug":"pop-anglaise","taxonomy":"category","parent":20,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecrits Num\u00e9riques - Rozenn Dupont\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/category\\\/pop\\\/pop-anglaise\\\/\",\"url\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/category\\\/pop\\\/pop-anglaise\\\/\",\"name\":\"Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/category\\\/pop\\\/pop-anglaise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/category\\\/pop\\\/pop-anglaise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pop\",\"item\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/category\\\/pop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pop anglaise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/#website\",\"url\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/\",\"name\":\"Ecrits Num\u00e9riques - Rozenn Dupont\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/webcom.iutlan.univ-rennes1.fr\\\/rozdupont\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont","og_url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/","og_site_name":"Ecrits Num\u00e9riques - Rozenn Dupont","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/","url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/","name":"Archives des Pop anglaise - Ecrits Num\u00e9riques - Rozenn Dupont","isPartOf":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#website"},"breadcrumb":{"@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/pop-anglaise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/"},{"@type":"ListItem","position":2,"name":"Pop","item":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/category\/pop\/"},{"@type":"ListItem","position":3,"name":"Pop anglaise"}]},{"@type":"WebSite","@id":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/#website","url":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/","name":"Ecrits Num\u00e9riques - Rozenn Dupont","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/categories\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/categories\/20"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rozdupont\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}