{"id":5579,"date":"2026-03-31T08:11:08","date_gmt":"2026-03-31T06:11:08","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/paguilcher\/?p=305"},"modified":"2026-04-08T17:15:23","modified_gmt":"2026-04-08T15:15:23","slug":"lujipeka-en-tournee-un-ete-place-sous-le-signe-des-festivals","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/2026\/03\/31\/lujipeka-en-tournee-un-ete-place-sous-le-signe-des-festivals\/","title":{"rendered":"Lujipeka, en tourn\u00e9e : un \u00e9t\u00e9 plac\u00e9 sous le signe des festivals"},"content":{"rendered":"\n<p>R\u00e9v\u00e9l\u00e9 au sein du collectif Columbine, Lujipeka s\u2019impose aujourd\u2019hui comme l\u2019une des figures marquantes de la sc\u00e8ne rap fran\u00e7aise. Avec son style m\u00ealant pop, rap et introspection, il touche une g\u00e9n\u00e9ration enti\u00e8re gr\u00e2ce \u00e0 des textes sinc\u00e8res et accessibles. Apr\u00e8s plusieurs succ\u00e8s et une pause remarqu\u00e9e, l\u2019artiste signe un retour tr\u00e8s attendu avec de nouveaux titres et une grande tourn\u00e9e en 2026 !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Une tourn\u00e9e ambitieuse en France et en Europe<\/h3>\n\n\n\n<p>\u00c0 partir de f\u00e9vrier 2026, Lujipeka entame une tourn\u00e9e d\u2019envergure avec plus de 30 dates \u00e0 travers la France, la Suisse et la Belgique.<br>Ce retour sur sc\u00e8ne marque une nouvelle \u00e9tape dans sa carri\u00e8re, notamment avec l\u2019annonce d\u2019un concert \u00e9v\u00e9nement \u00e0 l\u2019Accor Arena \u00e0 Paris en novembre 2026, symbole de sa mont\u00e9e en puissance.<\/p>\n\n\n\n<p>Mais avant cette grande date, c\u2019est surtout pendant le printemps et l\u2019\u00e9t\u00e9 que l\u2019artiste va \u00e0 la rencontre de son public.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Une pr\u00e9sence remarqu\u00e9e dans les festivals<\/h3>\n\n\n\n<p>Durant la belle saison, Lujipeka multiplie les apparitions sur sc\u00e8ne, notamment dans plusieurs festivals importants :<\/p>\n\n\n\n<p>&#8211; <a href=\"https:\/\/www.festival-mythos.com\/programmation\/lujipeka\/\">Festival Mythos (avril 2026)<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.crd.corsica\/saison\/%F0%9D%90%81%F0%9D%90%80%F0%9D%90%92%F0%9D%90%93%F0%9D%90%88%F0%9D%90%80-alboru-east-side-festival\/\">&#8211; East Side Festival (2026)<\/a><\/p>\n\n\n\n<p>En parall\u00e8le, il encha\u00eene de nombreuses dates estivales dans diff\u00e9rentes villes fran\u00e7aises comme Bordeaux, Marseille ou encore N\u00eemes, dans des salles et \u00e9v\u00e9nements souvent proches de l\u2019ambiance festival. <\/p>\n\n\n\n<p>M\u00eame si toutes ses dates ne sont pas exclusivement des festivals, sa tourn\u00e9e adopte clairement l\u2019\u00e9nergie de ces grands rassemblements musicaux : public jeune, ambiance festive et proximit\u00e9 avec les fans.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un artiste g\u00e9n\u00e9rationnel<\/h3>\n\n\n\n<p>Ce succ\u00e8s sur sc\u00e8ne s\u2019explique par l\u2019univers unique de Lujipeka. \u00c0 travers ses morceaux, il aborde des th\u00e8mes comme le doute, la jeunesse, l\u2019amour ou encore le mal-\u00eatre, avec une \u00e9criture simple mais percutante.<\/p>\n\n\n\n<p>Son retour avec de nouveaux titres comme <em>Br\u00fbler Paris<\/em> ou <em>La Vie d\u2019Antonio<\/em> confirme son \u00e9volution artistique et son envie de se renouveler.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusion<\/h3>\n\n\n\n<p>Entre tourn\u00e9e nationale, festivals et concert \u00e9v\u00e9nement \u00e0 Paris, l\u2019ann\u00e9e 2026 s\u2019annonce comme un tournant majeur pour Lujipeka.<br>Tr\u00e8s attendu sur sc\u00e8ne cet \u00e9t\u00e9, il confirme son statut d\u2019artiste incontournable pour toute une g\u00e9n\u00e9ration.<\/p>\n\n\n\n<p><a href=\"https:\/\/aucard-tours.com\/?\">Il sera pr\u00e9sent au Aucard de Tours, \u00e0 Tours<\/a> en 2026 !<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9v\u00e9l\u00e9 au sein du collectif Columbine, Lujipeka s\u2019impose aujourd\u2019hui comme l\u2019une des figures marquantes de la sc\u00e8ne rap fran\u00e7aise. Avec son style m\u00ealant pop, rap et introspection, il touche une g\u00e9n\u00e9ration enti\u00e8re gr\u00e2ce \u00e0 des textes sinc\u00e8res et accessibles. Apr\u00e8s plusieurs succ\u00e8s et une pause remarqu\u00e9e, l\u2019artiste signe un retour tr\u00e8s attendu avec de nouveaux &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/2026\/03\/31\/lujipeka-en-tournee-un-ete-place-sous-le-signe-des-festivals\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Lujipeka, en tourn\u00e9e : un \u00e9t\u00e9 plac\u00e9 sous le signe des festivals\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-5579","post","type-post","status-publish","format-standard","hentry","category-rap"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/posts\/5579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/comments?post=5579"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/posts\/5579\/revisions"}],"predecessor-version":[{"id":5652,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/posts\/5579\/revisions\/5652"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/media?parent=5579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/categories?post=5579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/tags?post=5579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}