{"id":18,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/category\/artiste\/","name":"Artiste","slug":"artiste","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/rcarpierpier\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}