{"id":26,"date":"2024-10-16T10:53:12","date_gmt":"2024-10-16T08:53:12","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/?p=26"},"modified":"2024-10-16T10:53:12","modified_gmt":"2024-10-16T08:53:12","slug":"facebook-et-les-jeunes","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/2024\/10\/16\/facebook-et-les-jeunes\/","title":{"rendered":"Facebook et les jeunes"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.lefigaro.fr\/medias\/recommandations-ia-bons-plans-pres-de-chez-soi-comment-meta-tente-de-faire-revenir-les-jeunes-sur-facebook-20241008?msockid=283aa30592e3683e1738b0f793a4698a\">Recommandations, IA, bons plans pr\u00e8s de chez soi&#8230; Comment Meta tente de faire revenir les jeunes sur Facebook (lefigaro.fr)<\/a><\/p>\n\n\n\n<p>Malgr\u00e9 le fait qu\u2019ils aient f\u00eat\u00e9 leur 20ans cette ann\u00e9e, Facebook n\u2019a pas su maintenir une audience jeune sur sa plate-forme. En effet, nous pouvons constater sur cet article publi\u00e9 par Le Figaro, que seulement 1 tiers des ados sont sur Facebook.<\/p>\n\n\n\n<p>J\u2019ai choisis cet article puisqu\u2019il m\u2019a paru int\u00e9ressant de constater tout les efforts d\u00e9ploy\u00e9 par Facebook afin de faire de la g\u00e9n\u00e9ration Z sa nouvelle priorit\u00e9. En effet, nous pouvons observer les diff\u00e9rentes strat\u00e9gies qu\u2019ils ont d\u00e9cid\u00e9 de mettre en place afin d\u2019atteindre leur objectif.<\/p>\n\n\n\n<p>Ainsi, ils d\u00e9veloppent par exemple un espace qui rassemblerait des lieux et activit\u00e9s \u00e0 proximit\u00e9 de l\u2019internaute, ils proposent des vid\u00e9os en liens avec les centres d\u2019int\u00e9r\u00eats de l\u2019utilisateur, et ils reproduisent m\u00eame les fameuses notes instagram permettant de partager son humeur sur le moment pr\u00e9sent. De plus, Meta compte \u00e9galement d\u00e9velopper l\u2019intelligence artificielle, tr\u00e8s utilis\u00e9e par les jeunes, sur Facebook.<\/p>\n\n\n\n<p>Nous pouvons alors constater que Meta reprend les codes de ses applications les plus populaires aupr\u00e8s des jeunes, tels que Instagram ou encore Tiktok, afin d\u2019attirer plus de jeunes sur Facebook.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.community-manager.fr\/tiktok-marques-jeunes\/\">TikTok, le nouveau terrain de jeu des marques jeunes (community-manager.fr)<\/a><\/p>\n\n\n\n<p>Cependant, cet article reste limit\u00e9 puisqu\u2019il n\u2019explique pas v\u00e9ritablement pourquoi il est si important pour Facebook de r\u00e9cup\u00e9rer une audience plus jeune. C\u2019est pour cela que nous pouvons mettre en lien cet article avec un autre article publi\u00e9 sur un site adress\u00e9 aux community managers, et qui aborde le sujet de TikTok et de sa communaut\u00e9 tr\u00e8s jeune. En effet, cet article permet de comprendre ce qu\u2019une communaut\u00e9 jeune apporte \u00e0 une plate-forme. Ainsi, nous comprenons par exemple que TikTok est tr\u00e8s vis\u00e9 par les marques jeunes, puisque la moiti\u00e9 des utilisateurs ont moins de 24ans, constituant alors un excellent moyen de communiquer aupr\u00e8s de leur cible principale. Nous pouvons alors comprendre que les objectifs pr\u00e9sent\u00e9s dans le premier article ont pour but de permettre \u00e0 Facebook de s\u2019imposer, tout comme Tiktok, comme une plateforme de choix pour les marques qui cherchent \u00e0 attirer et \u00e0 engager un jeune public.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.lemonde.fr\/pixels\/article\/2024\/10\/06\/pour-les-reseaux-sociaux-la-fin-d-un-regne_6344843_4408996.html\">Pour les r\u00e9seaux sociaux, la fin d\u2019un r\u00e8gne&nbsp;? (lemonde.fr)<\/a><\/p>\n\n\n\n<p>Enfin, il m\u2019a paru important de porter attention \u00e0 cet article du Monde, afin de comprendre que notre fa\u00e7on d\u2019utiliser les r\u00e9seaux sociaux a chang\u00e9, et qu\u2019ainsi les marques et les groupes tel que Meta doivent s\u2019adapter \u00e0 ce changement.<\/p>\n\n\n\n<p>Ainsi, l\u2019article met l\u2019accent sur le fait que les utilisateurs des r\u00e9seaux sociaux ne publient plus, mais pr\u00e9f\u00e8re les stories ainsi que les messageries priv\u00e9s. Cela entra\u00eene la progression de certains r\u00e9seaux sociaux comme Whatsapp par exemple. Meta r\u00e9pond \u00e0 ces changements en d\u00e9veloppant ses syst\u00e8me de messagerie priv\u00e9, comme avec les groupes Facebook ou la cr\u00e9ation de \u00ab&nbsp;communities&nbsp;\u00bb sur Youtube. Ainsi, si Meta souhaite attirer une communaut\u00e9 jeune sur sa plate-forme Facebook, ils doivent non seulement s\u2019inspirer de r\u00e9seaux sociaux comme TikTok, comme nous l\u2019avons vu dans le deuxi\u00e8me article, mais \u00e9galement rebondir face aux changements dans la mani\u00e8re dont les internautes utilisent les r\u00e9seaux sociaux. En effet, Tom Alison, directeur de&nbsp;Facebook, l\u2019\u00e9crivait lui-m\u00eame l\u2019an dernier&nbsp;: \u00ab&nbsp;Il y a eu&nbsp;un&nbsp;changement ces derni\u00e8res ann\u00e9es,&nbsp;les&nbsp;gens viennent davantage sur&nbsp;Facebook&nbsp;pour se divertir, d\u00e9couvrir quelque chose de nouveau, ou s\u2019informer sur ce qui se passe dans le monde.&nbsp;\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recommandations, IA, bons plans pr\u00e8s de chez soi&#8230; Comment Meta tente de faire revenir les jeunes sur Facebook (lefigaro.fr) Malgr\u00e9 le fait qu\u2019ils aient f\u00eat\u00e9 leur 20ans cette ann\u00e9e, Facebook n\u2019a pas su maintenir une audience jeune sur sa plate-forme&#8230;. <a class=\"more-link\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/2024\/10\/16\/facebook-et-les-jeunes\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"predecessor-version":[{"id":27,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/posts\/26\/revisions\/27"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/odurox\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}