{"id":9,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mveret\/tag\/festival\/","name":"festival","slug":"festival","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mveret\/wp-json\/wp\/v2\/tags\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mveret\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mveret\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mveret\/wp-json\/wp\/v2\/posts?tags=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}