{"id":5554,"date":"2026-03-31T09:08:55","date_gmt":"2026-03-31T07:08:55","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/?p=299"},"modified":"2026-04-22T20:33:36","modified_gmt":"2026-04-22T18:33:36","slug":"les-30-ans-de-matmatah-le-groupe-breton-qui-traverse-les-generations","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/2026\/03\/31\/les-30-ans-de-matmatah-le-groupe-breton-qui-traverse-les-generations\/","title":{"rendered":"Les 30 ans de Matmatah : le groupe breton qui traverse les g\u00e9n\u00e9rations"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5554\" class=\"elementor elementor-5554\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5afc7c5c e-flex e-con-boxed e-con e-parent\" data-id=\"5afc7c5c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-465cd3f8 elementor-widget elementor-widget-text-editor\" data-id=\"465cd3f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><em>Le groupe Matmatah f\u00eatait en octobre 2025 leurs 30 ans \u00e0 Paris lors d\u2019un concert exceptionnel \u00e0 l\u2019Accor Arena. Plus de 18 000 personnes \u00e9taient pr\u00e9sentes. L\u2019occasion de mettre en avant leur histoire riche et leurs albums marquants.\u00a0<\/em><\/strong><\/p>\n\n\n\n<p><strong>Mots cl\u00e9s : 30 ans &#8211; g\u00e9n\u00e9rations &#8211; rock &#8211; album &#8211; succ\u00e8s &#8211; parcours <em>\u00a0<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-content\/uploads\/2026\/03\/Capture-decran-2026-03-31-a-09.04.20-771x1024.png\" alt=\"\" class=\"wp-image-300\" style=\"aspect-ratio:0.752933189060743\"\/><figcaption class=\"wp-element-caption\">Site Cultura : <a href=\"https:\/\/www.cultura.com\/p-matmatah-30-ans-20-titres-12659703.html\">https:\/\/www.cultura.com\/p-matmatah-30-ans-20-titres-12659703.html<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-content\/uploads\/2026\/03\/2048-1024x652.webp\" alt=\"\" class=\"wp-image-301\" style=\"aspect-ratio:1.5706129674706792;width:507px;height:auto\"\/><figcaption class=\"wp-element-caption\">Site Radio France : <a href=\"https:\/\/www.radiofrance.fr\/francebleu\/podcasts\/decibels-l-emission\/matmatah-fete-ses-30-ans-a-l-accor-arena-en-octobre-c-est-un-concert-que-l-on-ne-fera-qu-une-fois-2153510\">https:\/\/www.radiofrance.fr\/francebleu\/podcasts\/decibels-l-emission\/matmatah-fete-ses-30-ans-a-l-accor-arena-en-octobre-c-est-un-concert-que-l-on-ne-fera-qu-une-fois-2153510<\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-content\/uploads\/2026\/03\/Capture-decran-2026-03-31-a-09.08.20-1024x661.png\" alt=\"\" class=\"wp-image-303\" style=\"aspect-ratio:1.549220762212424;width:503px;height:auto\"\/><figcaption class=\"wp-element-caption\">Site Le T\u00e9l\u00e9gramme : <a href=\"https:\/\/www.letelegramme.fr\/finistere\/brest-29200\/trente-ans-de-matmatah-a-bercy-entre-energie-et-communion-diaporama-6907390.php\">https:\/\/www.letelegramme.fr\/finistere\/brest-29200\/trente-ans-de-matmatah-a-bercy-entre-energie-et-communion-diaporama-6907390.php<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>N\u00e9 en 1995 \u00e0 Brest, le groupe se forme autour de quatre amis qui veulent simplement jouer pour le plaisir. Tr\u00e8s vite, leur m\u00e9lange de rock, de folk et d\u2019influences celtiques s\u00e9duit. En 1998, leur premier album <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/3Jc7BaQeEeWq1KwDXmbS8g?si=vipUTymNRGKs4msSV1qtfQ\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/3Jc7BaQeEeWq1KwDXmbS8g?si=vipUTymNRGKs4msSV1qtfQ\">La Ouache<\/a><\/em> explose. On y trouve <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/track\/3KK8E89uc9rl2EEhbFiELq?si=9796adb2959544c0\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/track\/3KK8E89uc9rl2EEhbFiELq?si=9796adb2959544c0\">L\u2019Apologie<\/a><\/em>, <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/track\/4TQxGBi80EZbm6COxwIcGR?si=0f13088525054eed\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/track\/4TQxGBi80EZbm6COxwIcGR?si=0f13088525054eed\">Lamb\u00e9 An Dro<\/a><\/em> et <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/track\/1XIuwgrZsB0FQpad2ZMVYa?si=f58e5b92c18e4ba8\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/track\/1XIuwgrZsB0FQpad2ZMVYa?si=f58e5b92c18e4ba8\">Emma<\/a><\/em>. Ces titres deviennent des classiques et installent Matmatah comme un groupe incontournable. Le public les adopte, et les concerts s\u2019encha\u00eenent.<\/p>\n\n\n\n<p>Leur parcours se poursuit avec plusieurs albums. <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/7J0LtldNzK7XWqvpdRJF3f?si=uP3-x7xMQfq_u4YAZL4ITw\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/7J0LtldNzK7XWqvpdRJF3f?si=uP3-x7xMQfq_u4YAZL4ITw\">Rebelote<\/a><\/em> sort en 2001, puis <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/3gj1xOYavgASUY1j27bTGZ?si=Aj-UDm9IS2-HMNKljQKtfg\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/3gj1xOYavgASUY1j27bTGZ?si=Aj-UDm9IS2-HMNKljQKtfg\">Archie Kramer<\/a><\/em> en 2004 et en 2007, <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/5sN0weTtwIRLDQmbvXG6XC?si=lqMbIkP_TQusVmt-y1ywJg\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/5sN0weTtwIRLDQmbvXG6XC?si=lqMbIkP_TQusVmt-y1ywJg\">La Cerise<\/a><\/em>. Apr\u00e8s cette p\u00e9riode intense, Matmatah fait une longue pause. Chacun continue son parcours de son c\u00f4t\u00e9 mais leurs chansons continuent de vivre. En 2017, ils reviennent avec <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/35KPICCxAelsB81JKpLZjN?si=th39k6iORhqFH8i22fcYfw\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/35KPICCxAelsB81JKpLZjN?si=th39k6iORhqFH8i22fcYfw\">Plates Coutures<\/a><\/em> qui marque leur retour en force.<\/p>\n\n\n\n<p><strong>Trois d\u00e9cennies de musique et de succ\u00e8s<\/strong><\/p>\n\n\n\n<p>Leur son m\u00e9lange guitares puissantes, rythmes \u00e9nergiques et touches celtiques. Leurs textes sont simples, parfois ironiques, souvent critiques. Ils parlent de la soci\u00e9t\u00e9, des exc\u00e8s, des illusions. En 2023, ils d\u00e9voilent <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/6cy4xBhCaRlVpFo7Ap1Kvd?si=VmjDf-WQSLeDrmal3qUPSw\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/6cy4xBhCaRlVpFo7Ap1Kvd?si=VmjDf-WQSLeDrmal3qUPSw\">Miscellan\u00e9es Bissextiles<\/a><\/em>, un album qui montre \u00e0 nouveau leur identit\u00e9 pr\u00e8s de 30 ans plus tard.<\/p>\n\n\n\n<p>Le groupe a re\u00e7u plusieurs r\u00e9compenses au fil de ces ann\u00e9es. Leur plus grande distinction arrive en 1998, avec le prix de la \u201cR\u00e9v\u00e9lation du public\u201d aux <a href=\"https:\/\/www.lesvictoiresdelamusique.fr\/victoires-varietes.php\" data-type=\"link\" data-id=\"https:\/\/www.lesvictoiresdelamusique.fr\/victoires-varietes.php\">Victoires de la Musique<\/a>. Plusieurs de leurs albums sont certifi\u00e9s or ou platine, notamment <em><a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/3Jc7BaQeEeWq1KwDXmbS8g?si=vipUTymNRGKs4msSV1qtfQ\" data-type=\"link\" data-id=\"https:\/\/open.spotify.com\/intl-fr\/album\/3Jc7BaQeEeWq1KwDXmbS8g?si=vipUTymNRGKs4msSV1qtfQ\">La Ouache<\/a><\/em>. Mais leur v\u00e9ritable succ\u00e8s, ce sont les milliers de fans derri\u00e8re eux, vingt ou trente ans apr\u00e8s leurs d\u00e9buts.<\/p>\n\n\n\n<p>\u201c\u00c7a commence donc par une blague et l\u00e0 on y est\u201d, commente Tristan Nihouarn sur le journal <a href=\"https:\/\/www.leparisien.fr\/culture-loisirs\/musique\/notre-tube-cetait-un-piege-matmatah-fete-ses-30-ans-avec-un-concert-geant-a-laccor-arena-10-10-2025-HU54ZIPYPZG3NAJDGFBZTRVDFQ.php\" data-type=\"link\" data-id=\"https:\/\/www.leparisien.fr\/culture-loisirs\/musique\/notre-tube-cetait-un-piege-matmatah-fete-ses-30-ans-avec-un-concert-geant-a-laccor-arena-10-10-2025-HU54ZIPYPZG3NAJDGFBZTRVDFQ.php\">Le Parisien<\/a>. Aujourd\u2019hui, Matmatah f\u00eate ses 30 ans. 30 ans d\u2019existence et de rock. Des chansons qui ont travers\u00e9 les g\u00e9n\u00e9rations. \u00ab\u00a0C\u2019est marrant car ce sont des chansons qui ont travers\u00e9 les g\u00e9n\u00e9rations. On a arr\u00eat\u00e9 pendant neuf ans (de 2007 \u00e0 2016) et quand on a repris, on a vu une nouvelle g\u00e9n\u00e9ration arriver avec des 15\/20 ans au premier rang. On se demandait d\u2019o\u00f9 ils sortaient !\u00a0\u00bb d\u00e9clare le groupe sur <a href=\"https:\/\/france3-regions.franceinfo.fr\/bretagne\/finistere\/brest\/une-occasion-unique-de-contempler-les-visages-de-notre-public-matmatah-fait-le-grand-show-a-bercy-pour-ses-30-ans-3268079.html\" data-type=\"link\" data-id=\"https:\/\/france3-regions.franceinfo.fr\/bretagne\/finistere\/brest\/une-occasion-unique-de-contempler-les-visages-de-notre-public-matmatah-fait-le-grand-show-a-bercy-pour-ses-30-ans-3268079.html\">France 3<\/a>. Apr\u00e8s trois d\u00e9cennies, le groupe prouve qu\u2019il reste une valeur s\u00fbre du rock fran\u00e7ais.\u00a0<\/p>\n\n\n\n<p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le groupe Matmatah f\u00eatait en octobre 2025 leurs 30 ans \u00e0 Paris lors d\u2019un concert exceptionnel \u00e0 l\u2019Accor Arena. Plus de 18 000 personnes \u00e9taient pr\u00e9sentes. L\u2019occasion de mettre en avant leur histoire riche et leurs albums marquants.\u00a0 Mots cl\u00e9s&#8230; <a class=\"more-link\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/2026\/03\/31\/les-30-ans-de-matmatah-le-groupe-breton-qui-traverse-les-generations\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,23],"tags":[],"class_list":["post-5554","post","type-post","status-publish","format-standard","hentry","category-folk-rock","category-rock","category-rock-celtique"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts\/5554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/comments?post=5554"}],"version-history":[{"count":7,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts\/5554\/revisions"}],"predecessor-version":[{"id":5721,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts\/5554\/revisions\/5721"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/media?parent=5554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories?post=5554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/tags?post=5554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}