{"id":33,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/category\/pop\/pop-anglaise\/","name":"Pop Anglaise","slug":"pop-anglaise","taxonomy":"category","parent":20,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories\/20"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}