{"id":20,"count":8,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/category\/pop\/","name":"Pop","slug":"pop","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/mthuillier\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}