{"id":40,"date":"2024-10-16T22:57:52","date_gmt":"2024-10-16T20:57:52","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/?p=40"},"modified":"2024-10-16T22:57:52","modified_gmt":"2024-10-16T20:57:52","slug":"lia-dans-la-prevision-meteo-et-climatique-vers-une-revolution-technologique","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/2024\/10\/16\/lia-dans-la-prevision-meteo-et-climatique-vers-une-revolution-technologique\/","title":{"rendered":"L\u2019IA dans la pr\u00e9vision m\u00e9t\u00e9o et climatique\u00a0: vers une r\u00e9volution technologique\u00a0?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2-1024x576.png\" alt=\"\" class=\"wp-image-41\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2-1024x576.png 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2-300x169.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2-768x432.png 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2-480x270.png 480w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/10\/image-2.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<a class=\"wp-block-read-more\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/2024\/10\/16\/lia-dans-la-prevision-meteo-et-climatique-vers-une-revolution-technologique\/\" target=\"_self\">https:\/\/www.blogdumoderateur.com\/ia-prevision-meteo-climat\/<span class=\"screen-reader-text\">\u00a0: L\u2019IA dans la pr\u00e9vision m\u00e9t\u00e9o et climatique\u00a0: vers une r\u00e9volution technologique\u00a0?<\/span><\/a>\n\n\n<p>\u00c0 la base j&rsquo;avais choisi un article concernant la collaboration entre l&rsquo;IAS et Meta. N&rsquo;arrivant pas \u00e0 traiter le sujet de mani\u00e8re claire. J&rsquo;ai d\u00e9cider de changer avec le sujet de l&rsquo;IA dans la pr\u00e9vision m\u00e9t\u00e9o et climatique. J&rsquo;ai choisi ce sujet car je le trouvais int\u00e9ressant puisqu&rsquo;il parle d&rsquo;un nouveau concept, peut \u00eatre l&rsquo;avenir, et de la m\u00e9t\u00e9o qui fait partie de notre quotidien et qui concerne, quiconque dans le monde.<\/p>\n\n\n\n<p>\u00c0 travers cet article, je me suis pos\u00e9e diff\u00e9rentes questions :  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;IA est-ce une source fiable ? <\/li>\n\n\n\n<li>L&rsquo;IA est-ce vraiment une r\u00e9volution technologique ? <\/li>\n\n\n\n<li>L&rsquo;IA est-ce une menace pour les emplois ? <\/li>\n<\/ul>\n\n\n\n<p><strong>L&rsquo;IA est une source fiable ? <\/strong><\/p>\n\n\n\n<p>L&rsquo;IA a \u00e9t\u00e9 invent\u00e9e en 1956 par John Mc Carthy. Cet homme est un informaticien am\u00e9ricain n\u00e9 en 1927 et mort en 2011. C&rsquo;est un des principal pionniers de l&rsquo;invention de l&rsquo;IA avec Marvin Lee Minsky. <\/p>\n\n\n\n<p>Les syst\u00e8mes d&rsquo;IA sont con\u00e7us et d\u00e9velopp\u00e9s par des humains qui peuvent commettre des erreurs dans le codage et la conception. \u00ab\u00a0L\u2019IA peut mettre \u00e0 mal nos valeurs, nos droits, nos normes et nos comportements. Le risque est que certains en viennent \u00e0 ne plus r\u00e9fl\u00e9chir par eux m\u00eames et se servent en premier lieu de l\u2019IA.\u00a0\u00bb selon <a href=\"https:\/\/blogpeda.region-academique-nouvelle-aquitaine.fr\/19-tulle-college-victor-hugo\/2024\/03\/21\/lia-est-elle-vraiment-fiable\/#:~:text=L'IA%20est%20une%20source,premier%20lieu%20de%20l'IA.\">https:\/\/blogpeda.region-academique-nouvelle-aquitaine.fr\/19-tulle-college-victor-hugo\/2024\/03\/21\/lia-est-elle-vraiment-fiable\/#:~:text=L&rsquo;IA%20est%20une%20source,premier%20lieu%20de%20l&rsquo;IA.<\/a><\/p>\n\n\n\n<p>Selon deux chercheurs de NY University,\u00a0Gary Marcus\u00a0et Ernest Davis, les progr\u00e8s spectaculaires du \u00ab\u00a0deep learning\u00a0\u00bb (apprentissage automatique profond) et l&rsquo;engouement massif qu&rsquo;ils ont entra\u00een\u00e9 masquent une r\u00e9alit\u00e9 importante\u00a0:\u00a0<em>\u00ab\u00a0On ne peut pas faire confiance \u00e0 l&rsquo;IA telle qu&rsquo;elle existe aujourd&rsquo;hui.\u00a0\u00bb<\/em><\/p>\n\n\n\n<p>Des erreurs ont \u00e9t\u00e9 commises avec l&rsquo;IA. Plus ou moins graves comme des biais dans les jeux de donn\u00e9es qui peuvent cr\u00e9er des discriminations mais encore\u00a0l&rsquo;accident mortel d&rsquo;un v\u00e9hicule autonome d&rsquo;Uber\u00a0en mars\u00a02018, parce que le logiciel n&rsquo;avait pas r\u00e9ussi \u00e0 identifier correctement la victime, une femme qui traversait la route de nuit en poussant son v\u00e9lo.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.lesechos.fr\/idees-debats\/sciences-prospective\/peut-on-vraiment-faire-confiance-a-lintelligence-artificielle-1150745\">https:\/\/www.lesechos.fr\/idees-debats\/sciences-prospective\/peut-on-vraiment-faire-confiance-a-lintelligence-artificielle-1150745<\/a><\/p>\n\n\n\n<p><strong>L&rsquo;IA est-ce vraiment une r\u00e9volution technologique ? <\/strong><\/p>\n\n\n\n<p>Oui et non. Dans certains domaines jug\u00e9s sans cons\u00e9quences graves, comme l&rsquo;am\u00e9lioration grammaticale d&rsquo;un texte, l&rsquo;IA a sa place. Mais dans d&rsquo;autres domaines, elle n&rsquo;est pas assez exp\u00e9riment\u00e9e. Par ailleurs l&rsquo;IA est un danger pour l&rsquo;humain. Elle nous enl\u00e8ve la comp\u00e9tence de r\u00e9flexion, de lecture, de recherche. Elle nous donne une r\u00e9ponse toute faite qui est impersonnelle. Cependant elle nous permet de gagner du temps dans certains contextes. <\/p>\n\n\n\n<p>En 2024, environ 35% des entreprises mondiales utilisent l&rsquo;IA dans leurs op\u00e9rations. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.hostinger.fr\/tutoriels\/statistiques-ia#:~:text=Quel%20pourcentage%20d'entreprises%20utilisent,IA%20dans%20un%20avenir%20proche.\">https:\/\/www.hostinger.fr\/tutoriels\/statistiques-ia#:~:text=Quel%20pourcentage%20d&rsquo;entreprises%20utilisent,IA%20dans%20un%20avenir%20proche.<\/a><\/p>\n\n\n\n<p><strong>L&rsquo;IA est-ce une menace pour les emplois ? <\/strong><\/p>\n\n\n\n<p>Selon le site Hostinger tutoriels l&rsquo;IA cr\u00e9era 133 millions de nouveaux emplois d\u2019ici 2030. Aussi, elle contribuera \u00e0 plus de 15,7 trillions de dollars \u00e0 l\u2019\u00e9conomie mondiale d\u2019ici 2030. <\/p>\n\n\n\n<p>Ce n\u2019est pas n\u00e9cessairement une question de perte d\u2019emploi, c\u2019est une question de transformation de t\u00e2ches. Il y aurait une d\u00e9qualification du fait qu&rsquo;il y aura plusieurs t\u00e2ches automatis\u00e9es. Donc une baisse de salaire. <\/p>\n\n\n\n<p><strong>Conclusion<\/strong> : <\/p>\n\n\n\n<p>L&rsquo;IA pour la pr\u00e9vision m\u00e9t\u00e9o et climatique ne serait pas un outil fiable pour le moment. Dans l&rsquo;article du BDM, il parle de \u00ab\u00a0bo\u00eete noire\u00a0\u00bb. En effet, l&rsquo;IA ne conserve pas les donn\u00e9es, alors lors d&rsquo;une erreur commise, par exemple, lors de la pr\u00e9vision d&rsquo;une catastrophe naturelle, serait lourde de cons\u00e9quences. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 la base j&rsquo;avais choisi un article concernant la collaboration entre l&rsquo;IAS et Meta. N&rsquo;arrivant pas \u00e0 traiter le sujet de mani\u00e8re claire. J&rsquo;ai d\u00e9cider de changer avec le sujet de l&rsquo;IA dans la pr\u00e9vision m\u00e9t\u00e9o et climatique. J&rsquo;ai choisi ce sujet car je le trouvais int\u00e9ressant puisqu&rsquo;il parle d&rsquo;un nouveau concept, peut \u00eatre l&rsquo;avenir, et de la m\u00e9t\u00e9o qui fait partie de notre quotidien et qui concerne, quiconque dans le monde. \u00c0 travers cet article, je me suis pos\u00e9e&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/2024\/10\/16\/lia-dans-la-prevision-meteo-et-climatique-vers-une-revolution-technologique\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":2,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"predecessor-version":[{"id":43,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/40\/revisions\/43"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}