{"id":245,"date":"2024-12-15T12:11:09","date_gmt":"2024-12-15T11:11:09","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/?p=245"},"modified":"2024-12-15T12:11:09","modified_gmt":"2024-12-15T11:11:09","slug":"sur-la-piste-du-pere-noel-google-propose-un-adorable-site-web-pour-les-fetes","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/2024\/12\/15\/sur-la-piste-du-pere-noel-google-propose-un-adorable-site-web-pour-les-fetes\/","title":{"rendered":"Sur la piste du P\u00e8re No\u00ebl\u00a0: Google propose un adorable site web pour les f\u00eates"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"498\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10-1024x498.png\" alt=\"\" class=\"wp-image-246\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10-1024x498.png 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10-300x146.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10-768x373.png 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10-555x270.png 555w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-10.png 1300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Associer l&rsquo;ambiance de No\u00ebl actuelle, \u00e0 la communication : voil\u00e0 ce qui a motiv\u00e9 mon choix de <a href=\"https:\/\/www.blogdumoderateur.com\/piste-pere-noel-google-site-web-fetes\/\" data-type=\"link\" data-id=\"https:\/\/www.blogdumoderateur.com\/piste-pere-noel-google-site-web-fetes\/\">cet article.<\/a> Au d\u00e9part, le titre ne m\u2019inspirait pas vraiment \u00e0 me poser des questions. Et puis, je me suis dit : \u00ab\u00a0Et si ce genre de situation \u00e9tait justement une occasion id\u00e9ale pour d\u00e9couvrir des informations auxquelles on ne penserait pas \u00e0 premi\u00e8re vue ?\u00a0\u00bb J\u2019esp\u00e8re qu\u2019apr\u00e8s avoir lu cet article, vous laisserez \u00e9chapper un petit \u00ab\u00a0ho ho ho\u00a0\u00bb de satisfaction ! <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c0 partir de quel \u00e2ge les enfants surfent sur <strong>internet<\/strong> ? Quel est l&rsquo;\u00e2ge moyen des plus grands consommateurs d&rsquo;internet ? <\/li>\n\n\n\n<li>Et qu&rsquo;en est-il des<strong> jeux vid\u00e9os<\/strong> ? <\/li>\n\n\n\n<li>Y&rsquo;a t-il un aspect <strong>marketing<\/strong> derri\u00e8re la cr\u00e9ation des jeux vid\u00e9o ? <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 partir de quel \u00e2ge les enfants surfent sur internet ? Quel est l&rsquo;\u00e2ge moyen des plus grands consommateurs d&rsquo;internet ? <\/h2>\n\n\n\n<p>Selon le site <a href=\"https:\/\/www.pass-santejeunes-bourgogne-franche-comte.org\/quel-age-pour-les-ecrans-reperes-temporels\/#:~:text=Ce%20n'est%20que%20vers,entre%206%20et%209%20ans.\" data-type=\"link\" data-id=\"https:\/\/www.pass-santejeunes-bourgogne-franche-comte.org\/quel-age-pour-les-ecrans-reperes-temporels\/#:~:text=Ce%20n'est%20que%20vers,entre%206%20et%209%20ans.\">Pass Sant\u00e9 Jeunes<\/a>, les enfants \u00e2g\u00e9s de 9 ans poss\u00e8de la capacit\u00e9 de surfer sur internet. Il faut que l&rsquo;enfant poss\u00e8de les capacit\u00e9s cognitives et qu&rsquo;il ma\u00eetrise la lecture et l&rsquo;\u00e9criture. De 0 \u00e0 6 ans l&rsquo;enfant a un mode de lecture du monde bas\u00e9 sur sa propre exp\u00e9rience que l&rsquo;on appelle pens\u00e9e \u00e9gocentrique. Le processus de d\u00e9centration commence vers l&rsquo;\u00e2ge de 6 ans. C&rsquo;est \u00e0 ce moment l\u00e0 que l&rsquo;enfant va d\u00e9velopper des points de vues diff\u00e9rents du sien et d\u00e9couvrir les diff\u00e9rentes perspectives possibles. C&rsquo;est donc \u00e0 ce moment l\u00e0 que l&rsquo;utilisation d&rsquo;internet peut devenir dangereuse pour l&rsquo;enfant. <\/p>\n\n\n\n<p>Selon un article du <a href=\"https:\/\/www.lefigaro.fr\/medias\/les-15-24-ans-plus-gros-consommateurs-d-internet-en-france-20230216\" data-type=\"link\" data-id=\"https:\/\/www.lefigaro.fr\/medias\/les-15-24-ans-plus-gros-consommateurs-d-internet-en-france-20230216\">Figaro<\/a>, ce sont les jeunes de <strong>15 \u00e0 24 ans<\/strong> qui sont <strong>les plus grands consommateurs<\/strong> d&rsquo;internet. Ils y passent en moyenne 4 heures par jour, soit deux fois plus que la moyenne des Fran\u00e7ais. Ils passent 93% de leur temps \u00e0 surfer sur internet \u00e0 travers leur <strong>smartphone<\/strong>. 60% de ce temps est pass\u00e9 sur les <strong>r\u00e9seaux sociaux<\/strong>, et en majorit\u00e9 sur snapchat pour cette tranche d&rsquo;\u00e2ge (chiffres de 2022). Tik Tok restait derri\u00e8re snapchat \u00e0 10 points de diff\u00e9rence. Cependant aujourd&rsquo;hui, Tik Tok est l&rsquo;application la plus consult\u00e9e par les jeunes. Aussi, les <strong>applications de retouches<\/strong> photos et vid\u00e9os occupent une tr\u00e8s grande place dans ces chiffres. Leur utilisation a doubl\u00e9 en 3 ans. Pour finir, l&rsquo;application Be Real a conquis beaucoup de jeunes (900.000), notamment 80% des femmes \u00e2g\u00e9es de 20 ans. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11-1024x576.png\" alt=\"\" class=\"wp-image-247\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11-1024x576.png 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11-300x169.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11-768x432.png 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11-480x270.png 480w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-11.png 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Le<a href=\"https:\/\/www.bfmtv.com\/tech\/actualites\/reseaux-sociaux\/voici-les-reseaux-sociaux-preferees-des-francais-selon-leur-age_AN-202402090520.html\" data-type=\"link\" data-id=\"https:\/\/www.bfmtv.com\/tech\/actualites\/reseaux-sociaux\/voici-les-reseaux-sociaux-preferees-des-francais-selon-leur-age_AN-202402090520.html\"> top 5 des r\u00e9seaux sociaux<\/a> les plus utilis\u00e9s quotidiennement par les diff\u00e9rentes classes d&rsquo;\u00e2ges. \u00a9 M\u00e9diam\u00e9trie\u00a0<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Et qu&rsquo;en est-il des jeux vid\u00e9os ? <\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"765\" height=\"439\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-12.png\" alt=\"\" class=\"wp-image-248\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-12.png 765w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-12-300x172.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-12-471x270.png 471w\" sizes=\"(max-width: 765px) 100vw, 765px\" \/><\/figure>\n\n\n\n<p>Les jeux vid\u00e9os touchent toutes les tranches d&rsquo;\u00e2ge, avec 95 % des enfants (10-17 ans), 66 % des adultes (18 ans et plus) et 43 % des seniors (65 ans et plus), et une moyenne d&rsquo;\u00e2ge des joueurs de 39 ans. 52% de la population fran\u00e7aise jouent au moins 1 fois par semaine.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"562\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-13.png\" alt=\"\" class=\"wp-image-249\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-13.png 765w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-13-300x220.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-content\/uploads\/2024\/12\/image-13-368x270.png 368w\" sizes=\"(max-width: 765px) 100vw, 765px\" \/><\/figure>\n\n\n\n<p>Vous pouvez retrouver ces chiffres <a href=\"https:\/\/afjv.com\/news\/11554_chiffres-etude-francais-jeux-video-2024.htm#:~:text=Le%20jeu%20vid\u00e9o%20touche%20en,des%20joueurs%20de%2039%20ans.\" data-type=\"link\" data-id=\"https:\/\/afjv.com\/news\/11554_chiffres-etude-francais-jeux-video-2024.htm#:~:text=Le%20jeu%20vid\u00e9o%20touche%20en,des%20joueurs%20de%2039%20ans.\">ici<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Y&rsquo;a t-il un aspect marketing derri\u00e8re la cr\u00e9ation des jeux vid\u00e9o ? <\/h2>\n\n\n\n<p>L&rsquo;article de <a href=\"https:\/\/www.preferendum.fr\/blog\/linteret-du-gaming-dans-sa-strategie-marketing\" data-type=\"link\" data-id=\"https:\/\/www.preferendum.fr\/blog\/linteret-du-gaming-dans-sa-strategie-marketing\">Preferendum<\/a> met en avant l&rsquo;int\u00e9r\u00eat croissant du gaming dans les strat\u00e9gies de\u00a0<strong>marketing d&rsquo;influence<\/strong>\u00a0et de\u00a0<strong>communication<\/strong>, soulignant leur r\u00f4le dans l&rsquo;engagement et la notori\u00e9t\u00e9 des marques. <\/p>\n\n\n\n<p>Les jeux vid\u00e9o permettent aux marques de\u00a0<strong>cr\u00e9er des partenariats strat\u00e9giques<\/strong>\u00a0avec des influenceurs gaming ou de s&rsquo;int\u00e9grer dans des plateformes populaires comme\u00a0<em>Fortnite<\/em>\u00a0ou\u00a0<em>League of Legends<\/em>. Ces partenariats s&rsquo;inscrivent dans une <strong>strat\u00e9gie d&rsquo;influence cibl\u00e9e<\/strong>, particuli\u00e8rement efficace pour atteindre la\u00a0g\u00e9n\u00e9ration Z, grande consommatrice de contenu interactif et num\u00e9rique.<\/p>\n\n\n\n<p>Le\u00a0<strong>in-game advertising<\/strong>\u00a0permet une communication immersive en int\u00e9grant des marques directement dans l&rsquo;univers du jeu (panneaux publicitaires, skins personnalis\u00e9s, \u00e9v\u00e9nements sp\u00e9ciaux). Cette approche renforce la <strong>visibilit\u00e9<\/strong> de mani\u00e8re naturelle et en s&rsquo;adaptant aux attentes des joueurs pour une <strong>exp\u00e9rience authentique<\/strong>.<\/p>\n\n\n\n<p>Les marques de luxe, comme Louis Vuitton ou Longchamp, s&rsquo;associent \u00e0 l&rsquo;industrie du gaming pour\u00a0<strong>renforcer leur image aupr\u00e8s des jeunes publics<\/strong>. Ces collaborations, qui mettent en avant des valeurs partag\u00e9es comme l&rsquo;innovation et l&rsquo;exclusivit\u00e9, permettent d&rsquo;allier le prestige au caract\u00e8re innovant des jeux.<br>Le gaming permet aux marques de rassembler une communaut\u00e9 engag\u00e9e en s&rsquo;appuyant sur des valeurs partag\u00e9es et en cr\u00e9ant un sentiment de connexion et d&rsquo;appartenance autour de leur univers. Cela se traduit par des campagnes interactives et des <strong>collaborations<\/strong> avec des streamers ou des <strong>influenceurs<\/strong> qui amplifient le message de la marque.<\/p>\n\n\n\n<p>En s&rsquo;int\u00e9grant dans les \u00e9cosyst\u00e8mes gaming, les marques adoptent une approche innovante, m\u00ealant <strong>communication immersive<\/strong> et <strong>influence cibl\u00e9e<\/strong>. Le gaming devient un outil essentiel pour permettre aux entreprises de se<strong> rapprocher de leur public<\/strong>, tout en affirmant leur <strong>identit\u00e9<\/strong> et augmentant leur <strong>notori\u00e9t\u00e9<\/strong>.<\/p>\n\n\n\n<p>Dans le jeu\u00a0<em>Sur la piste du P\u00e8re No\u00ebl<\/em>, l&rsquo;univers festif de No\u00ebl est mis en avant, renfor\u00e7ant l\u2019attachement des joueurs \u00e0 cette c\u00e9l\u00e9bration. Cette approche cultive la <strong>dimension commerciale<\/strong> de No\u00ebl, incitant les joueurs \u00e0 s\u2019investir davantage dans des activit\u00e9s li\u00e9es \u00e0 la f\u00eate, comme la d\u00e9coration ou l&rsquo;achat des cadeaux. L&rsquo;immersion dans cet univers festif pourrait prolonger leur sensibilit\u00e9 \u00e0 l&rsquo;esprit de No\u00ebl, les encourageant \u00e0 <strong>consommer davantage<\/strong>. Ainsi, ce type de jeu constitue un<strong> levier strat\u00e9gique<\/strong> pour stimuler l\u2019<strong>engagement et les comportements d&rsquo;achat<\/strong> des joueurs pendant la saison des f\u00eates.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Mais ne serait-il pas dommage d&rsquo;allier magie de No\u00ebl et jeux vid\u00e9o ? Cela ne g\u00e2cherait-il pas ce moment annuel unique qui se veut imaginatif et propice au partage en famille, aussi bien pour les plus petits comme pour les plus grands ? <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Associer l&rsquo;ambiance de No\u00ebl actuelle, \u00e0 la communication : voil\u00e0 ce qui a motiv\u00e9 mon choix de cet article. Au d\u00e9part, le titre ne m\u2019inspirait pas vraiment \u00e0 me poser des questions. Et puis, je me suis dit : \u00ab\u00a0Et si ce genre de situation \u00e9tait justement une occasion id\u00e9ale pour d\u00e9couvrir des informations auxquelles on ne penserait pas \u00e0 premi\u00e8re vue ?\u00a0\u00bb J\u2019esp\u00e8re qu\u2019apr\u00e8s avoir lu cet article, vous laisserez \u00e9chapper un petit \u00ab\u00a0ho ho ho\u00a0\u00bb de satisfaction !&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/2024\/12\/15\/sur-la-piste-du-pere-noel-google-propose-un-adorable-site-web-pour-les-fetes\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-245","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":2,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/245\/revisions"}],"predecessor-version":[{"id":251,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/posts\/245\/revisions\/251"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/categories?post=245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lvleugels\/wp-json\/wp\/v2\/tags?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}