{"id":34,"date":"2024-11-07T08:37:33","date_gmt":"2024-11-07T07:37:33","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/?p=34"},"modified":"2024-11-07T08:37:33","modified_gmt":"2024-11-07T07:37:33","slug":"duolingo-et-sa-campagne-marketing-a-shanghai","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/2024\/11\/07\/duolingo-et-sa-campagne-marketing-a-shanghai\/","title":{"rendered":"Duolingo et sa campagne marketing \u00e0 Shanghai."},"content":{"rendered":"\n<p><a href=\"https:\/\/jai-un-pote-dans-la.com\/duolingo-investit-rues-shanghai-pour-activation-decalee\">https:\/\/jai-un-pote-dans-la.com\/duolingo-investit-rues-shanghai-pour-activation-decalee<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/JUPDLC-fred-farid-shanghai-duolingo-trick-or-streak.jpg-1-1024x536.webp\" alt=\"\" class=\"wp-image-40\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/JUPDLC-fred-farid-shanghai-duolingo-trick-or-streak.jpg-1-1024x536.webp 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/JUPDLC-fred-farid-shanghai-duolingo-trick-or-streak.jpg-1-300x157.webp 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/JUPDLC-fred-farid-shanghai-duolingo-trick-or-streak.jpg-1-768x402.webp 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/JUPDLC-fred-farid-shanghai-duolingo-trick-or-streak.jpg-1.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>image tir\u00e9e de l&rsquo;article ci-dessus<\/p>\n\n\n\n<p class=\"has-text-align-left\">Duolingo est une application qui permet d\u2019apprendre des langues de fa\u00e7on gratuite et ludique. Connu par son logo de chouette, elle propose un apprentissage journalier gr\u00e2ce \u00e0 des exercices de compr\u00e9hension et d&rsquo;expression \u00e9crite et orale.<\/p>\n\n\n\n<p class=\"has-text-align-left\">R\u00e9cemment, \u00e0 l\u2019occasion d\u2019halloween, l\u2019application a lanc\u00e9 une campagne en Chine dans la ville Shanghai, o\u00f9 les habitants ont pu observer et interagir avec des mascottes du hiboux Duolingo. Cette campagne marketing s\u2019appuie sur le principe de \u00ab&nbsp;streak&nbsp;\u00bb qui consiste \u00e0 compter les jours cons\u00e9cutifs d\u2019apprentissage qui vient remplacer le fameux \u00ab&nbsp;treat&nbsp;\u00bb de \u00ab&nbsp;trick or treat&nbsp;\u00bb maintenant remplac\u00e9 par \u00ab&nbsp;trick or streak&nbsp;\u00bb. Le but est d\u2019inciter les personnes \u00e0 r\u00e9aliser leur le\u00e7on le jour m\u00eame afin de prolonger leur s\u00e9rie, mais \u00e9galement de se faire plus conna\u00eetre chez les Chinois.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>De plus, un \u00e9v\u00e8nement tel qu\u2019halloween regroupe une \u00ab&nbsp;foule&nbsp;\u00bb, en effet beaucoup de personnes sortent dans les rues&nbsp;; celles-ci vont alors se prendre en photo avec la mascotte et partager ce contenu sur les r\u00e9seaux notamment Douyin qui correspond au Tik Tok fran\u00e7ais et RED.&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"474\" height=\"316\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/th.jpg.webp\" alt=\"\" class=\"wp-image-37\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/th.jpg.webp 474w, https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-content\/uploads\/2024\/11\/th.jpg-300x200.webp 300w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Cette strat\u00e9gie nous montre l\u2019importance des mascottes ou des \u00e9l\u00e9ments reconnaissables d\u2019une application qui font partie de l\u2019identit\u00e9 de celle-ci et qui va permettre une meilleure reconnaissance de la part du public. En effet, on humanise les marques avec des mascottes \u00ab&nbsp;vivantes&nbsp;\u00bb, elles permettent de prolonger le storytelling de la marque et nous rappelle l\u2019enfance avec des design souvent simple qui nous rappellent les doudous.&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p>Mais \u00e9galement le fait d\u2019utiliser des \u00e9v\u00e8nements devenus presque mondiaux pour repr\u00e9senter l\u2019application sont des fa\u00e7ons int\u00e9ressantes de communiquer.<\/p>\n<\/div>\n<\/div>\n\n\n<a class=\"wp-block-read-more\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/2024\/11\/07\/duolingo-et-sa-campagne-marketing-a-shanghai\/\" target=\"_self\"><a href=\"https:\/\/www.grapheine.com\/divers\/quelles-strategies-derriere-le-sourire-des-mascottes\">https:\/\/www.grapheine.com\/divers\/quelles-strategies-derriere-le-sourire-des-mascottes<\/a><span class=\"screen-reader-text\">\u00a0: Duolingo et sa campagne marketing \u00e0 Shanghai.<\/span><\/a>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/jai-un-pote-dans-la.com\/duolingo-investit-rues-shanghai-pour-activation-decalee image tir\u00e9e de l&rsquo;article ci-dessus Duolingo est une application qui permet d\u2019apprendre des langues de fa\u00e7on gratuite et ludique. Connu par son logo de chouette, elle propose un apprentissage journalier gr\u00e2ce \u00e0 des exercices de compr\u00e9hension et d&rsquo;expression \u00e9crite et orale. R\u00e9cemment, \u00e0 l\u2019occasion d\u2019halloween, l\u2019application a lanc\u00e9 une campagne en Chine dans la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":5,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"predecessor-version":[{"id":42,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/posts\/34\/revisions\/42"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/llancelotkei\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}