{"id":177,"date":"2026-01-09T09:06:46","date_gmt":"2026-01-09T08:06:46","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/?p=177"},"modified":"2026-01-09T09:09:45","modified_gmt":"2026-01-09T08:09:45","slug":"reddit-le-reseau-social-qui-plait-de-plus-en-plus-aux-jeunes","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/2026\/01\/09\/reddit-le-reseau-social-qui-plait-de-plus-en-plus-aux-jeunes\/","title":{"rendered":"Reddit, le r\u00e9seau social qui pla\u00eet de plus en plus aux jeunes."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"177\" class=\"elementor elementor-177\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cea0589 e-flex e-con-boxed e-con e-parent\" data-id=\"4cea0589\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26668270 elementor-widget elementor-widget-text-editor\" data-id=\"26668270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p>J\u2019ai choisi ce th\u00e8me pour mon troisi\u00e8me article car c\u2019est un sujet sur lequel j\u2019ai pu beaucoup m\u2019informer ces derniers temps, notamment pour la SAE gestion de donn\u00e9es. Reddit, r\u00e9seau social cr\u00e9e en 2005 par Steve Huffman et Alexis Ohanian, est en plein essor depuis quelques ann\u00e9es, notamment depuis la cr\u00e9ation de son application en 2017.(<a href=\"https:\/\/www.blogdumoderateur.com\/reddit-premiere-page-google-trafic-explose\/\">https:\/\/www.blogdumoderateur.com\/reddit-premiere-page-google-trafic-explose\/<\/a>)<\/p>\n\n<p class=\"wp-block-heading\">Selon un article de<em>J\u2019ai un pote dans la com (<\/em><a href=\"https:\/\/jai-un-pote-dans-la.com\/reddit-depasse-tiktok-au-royaume-uni\/\">https:\/\/jai-un-pote-dans-la.com\/reddit-depasse-tiktok-au-royaume-uni\/<\/a>), Reddit gagne des places dans le classement des r\u00e9seaux sociaux les plus utilis\u00e9s au Royaume-Uni, et surpasse certains g\u00e9ants du march\u00e9 comme Tiktok. Ainsi, il \u00ab\u00a0grimpe \u00e0 la quatri\u00e8me place\u00a0\u00bb. Fin 2024, reddit a annonc\u00e9 ces r\u00e9sultats trimestriels et d\u00e9clare avoir pr\u00e8s de 100 millions d&rsquo;utilisateurs actifs quotidiens. (https:\/\/www.reddit.com\/). Selon cet article de JUPDLC, ce r\u00e9seau conna\u00eet une aussi grande mont\u00e9e en puissance gr\u00e2ce \u00e0 la GenZ, notamment gr\u00e2ce a ses propositions de contenus vari\u00e9s (gaming, humour, beaut\u00e9,\u2026.). En effet, selon le rapport Meltwater 2026, la tranche d&rsquo;\u00e2ge qui utilise le plus Reddit sont les 16-24 ans (<a href=\"https:\/\/www.meltwater.com\/fr\/global-digital-trends\"><u>https:\/\/www.meltwater.com\/fr\/global-digital-trends<\/u><\/a>). Ainsi, face \u00e0 tous ces \u00e9l\u00e9ments, le Royaume-Uni devient le 3<sup>e<\/sup> pays ayant le plus d\u2019utilisateurs de Reddit, derri\u00e8re la Chine et les Etats-Unis et deva,t le Canada, le Br\u00e9sil ou encore la France. (<a href=\"https:\/\/backlinko.com\/reddit-users\"><u>https:\/\/bac\u00a0 klinko.com\/reddit-users<\/u><\/a>).<\/p>\n\n<p>En outre, si le r\u00e9seau conna\u00eet une aussi grande mont\u00e9e en popularit\u00e9, c\u2019est gr\u00e2ce \u00e0 la mise en avant dont il b\u00e9n\u00e9ficie par le moteur de recherche Google. Reddit devient une r\u00e9f\u00e9rence sur de nombreux sujets, et est souvent propos\u00e9s comme r\u00e9sultats aux recherches. (<a href=\"https:\/\/www.blogdumoderateur.com\/reddit-premiere-page-google-trafic-explose\/\"><u>https:\/\/www.blogdumoderateur.com\/reddit-premiere-page-google-trafic-explose\/<\/u><\/a>)<\/p>\n<p>MOUAZAN Laurine &#8211; COM1<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>J\u2019ai choisi ce th\u00e8me pour mon troisi\u00e8me article car c\u2019est un sujet sur lequel j\u2019ai pu beaucoup m\u2019informer ces derniers temps, notamment pour la SAE gestion de donn\u00e9es. Reddit, r\u00e9seau social cr\u00e9e en 2005 par Steve Huffman et Alexis Ohanian, est en plein essor depuis quelques ann\u00e9es, notamment depuis la cr\u00e9ation de son application en &hellip; <a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/2026\/01\/09\/reddit-le-reseau-social-qui-plait-de-plus-en-plus-aux-jeunes\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Reddit, le r\u00e9seau social qui pla\u00eet de plus en plus aux jeunes.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-177","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/posts\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":4,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/posts\/177\/revisions"}],"predecessor-version":[{"id":181,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/posts\/177\/revisions\/181"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/categories?post=177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lamouazan\/wp-json\/wp\/v2\/tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}