{"id":419,"date":"2025-01-20T18:38:39","date_gmt":"2025-01-20T17:38:39","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/?p=419"},"modified":"2026-04-01T13:55:25","modified_gmt":"2026-04-01T11:55:25","slug":"les-echos-le-parisien-medias-organise-une-masterclass-sur-le-campus-de-futurae","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/2025\/01\/20\/les-echos-le-parisien-medias-organise-une-masterclass-sur-le-campus-de-futurae\/","title":{"rendered":"Les Echos \u2013 Le Parisien M\u00e9dias organise une Masterclass sur le campus de Futurae"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-content\/uploads\/2025\/01\/Capture-decran-2025-01-20-a-18.33.23-1024x533.png\" alt=\"\" class=\"wp-image-420\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-content\/uploads\/2025\/01\/Capture-decran-2025-01-20-a-18.33.23-1024x533.png 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-content\/uploads\/2025\/01\/Capture-decran-2025-01-20-a-18.33.23-300x156.png 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-content\/uploads\/2025\/01\/Capture-decran-2025-01-20-a-18.33.23-768x400.png 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-content\/uploads\/2025\/01\/Capture-decran-2025-01-20-a-18.33.23.png 1340w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Le groupe Les Echos \u2013 Le Parisien M\u00e9dias affirme son engagement aupr\u00e8s de la nouvelle g\u00e9n\u00e9ration en cultivant son int\u00e9r\u00eat pour les secteurs des m\u00e9dias, de la communication et de la publicit\u00e9. Dans cette d\u00e9marche, il s\u2019est associ\u00e9 \u00e0 Futurae, \u00e9cole d\u00e9di\u00e9e aux industries cr\u00e9atives et aux m\u00e9tiers du num\u00e9rique, pour concevoir une Masterclass unique : \u00ab Introduction aux strat\u00e9gies m\u00e9dias, publicitaires et cr\u00e9atives \u00bb. Ce programme intensif de quatre jours a \u00e9t\u00e9 pens\u00e9 pour initier les \u00e9tudiants aux dynamiques complexes et passionnantes de l\u2019\u00e9cosyst\u00e8me m\u00e9diatique fran\u00e7ais. En plus de transmettre des savoirs concrets et des retours d\u2019exp\u00e9rience inspirants, ces rencontres ont favoris\u00e9 un dialogue constructif, offrant aux \u00e9tudiants l\u2019opportunit\u00e9 de s\u2019exprimer et de r\u00e9fl\u00e9chir \u00e0 leur r\u00f4le futur en tant qu\u2019acteurs cl\u00e9s de l\u2019industrie. Ce moment d\u2019\u00e9change, \u00e0 la crois\u00e9e de la p\u00e9dagogie et de l\u2019innovation, illustre l\u2019ambition du groupe de former et d\u2019accompagner les talents de demain.<\/p>\n\n\n\n<p><strong>Comment les \u00e9changes entre \u00e9tudiants et professionnels, comme ceux organis\u00e9s lors de cette masterclass, peuvent-ils enrichir les pratiques cr\u00e9atives et strat\u00e9giques dans le domaine de la communication ?<\/strong><\/p>\n\n\n\n<p>Les \u00e9changes entre \u00e9tudiants et professionnels, tels que ceux propos\u00e9s lors de la masterclass organis\u00e9e par Les Echos \u2013 Le Parisien M\u00e9dias, constituent une v\u00e9ritable source d\u2019enrichissement pour les pratiques cr\u00e9atives et strat\u00e9giques en communication. D\u2019un c\u00f4t\u00e9, les \u00e9tudiants, souvent en phase avec les nouvelles tendances et les attentes des jeunes g\u00e9n\u00e9rations, apportent une vision novatrice et audacieuse. De l\u2019autre, les professionnels partagent leur exp\u00e9rience et leur expertise, offrant des cadres strat\u00e9giques solides et des outils concrets pour transformer ces id\u00e9es en solutions applicables. Ces \u00e9changes permettent \u00e9galement de connecter les approches th\u00e9oriques acquises dans le cadre acad\u00e9mique aux r\u00e9alit\u00e9s op\u00e9rationnelles du terrain, favorisant ainsi l\u2019\u00e9mergence de solutions cr\u00e9atives adapt\u00e9es aux d\u00e9fis actuels du march\u00e9. De plus,&nbsp; ils aident les \u00e9tudiants \u00e0 mieux appr\u00e9hender les \u00e9volutions rapides et les enjeux pratiques du secteur, tout en encourageant les professionnels \u00e0 repenser leurs pratiques \u00e0 travers le prisme des nouvelles g\u00e9n\u00e9rations.<\/p>\n\n\n\n<p>Enfin, ces interactions posent les bases de relations professionnelles durables, ouvrant la voie \u00e0 d\u2019\u00e9ventuelles collaborations futures et nourrissant une dynamique continue d\u2019apprentissage et d\u2019innovation.<\/p>\n\n\n\n<p>Selon l\u2019article : <a href=\"https:\/\/fst.univ-lorraine.fr\/newsletter-05-rencontres-entre-etudiants-et-professionnels?utm\">univ-lorraine<\/a> : <\/p>\n\n\n\n<p>\u201cLes rencontres entre professionnels et \u00e9tudiants sont avantageuses pour les deux parties\u201d<\/p>\n\n\n\n<p><strong>Quels sont les principaux d\u00e9fis auxquels les futurs professionnels de la communication doivent se pr\u00e9parer, compte tenu des transformations actuelles du march\u00e9 m\u00e9diatique et publicitaire ?<\/strong><\/p>\n\n\n\n<p>Les futurs professionnels de la communication doivent se pr\u00e9parer \u00e0 plusieurs d\u00e9fis cruciaux. Les outils num\u00e9riques et les plateformes de communication \u00e9voluent \u00e0 un rythme rapide, obligeant les experts \u00e0 rester \u00e0 l&rsquo;avant-garde des innovations, telles que l&rsquo;intelligence artificielle et la r\u00e9alit\u00e9 augment\u00e9e, afin de concevoir des strat\u00e9gies pertinentes et efficaces. De plus, la collecte et l\u2019analyse des donn\u00e9es sont devenues essentielles pour \u00e9laborer des campagnes cibl\u00e9es et en mesurer l&rsquo;impact. Les professionnels devront \u00e9galement ma\u00eetriser les enjeux li\u00e9s \u00e0 la gestion et \u00e0 la protection des donn\u00e9es personnelles, dans un cadre r\u00e9glementaire de plus en plus strict. Par ailleurs, la communication doit d\u00e9sormais \u00eatre abord\u00e9e sous l\u2019angle de la transparence et de la responsabilit\u00e9 sociale. Ils devront ainsi mettre en place des campagnes qui respectent les enjeux soci\u00e9taux, tout en \u00e9tant conscients de leur influence sur les valeurs et comportements des consommateurs. Finalement, face \u00e0 une demande croissante des consommateurs pour des marques authentiques, \u00e9thiques et responsables, les professionnels devront naviguer avec cr\u00e9ativit\u00e9 et innovation pour r\u00e9pondre \u00e0 ces attentes tout en restant fid\u00e8les \u00e0 leurs engagements.<\/p>\n\n\n\n<p>Selon l\u2019\u00e9tude de Mckinsey, trouv\u00e9 sur le site<a href=\"https:\/\/vorecol.com\/fr\/blogs\/blog-levolution-des-attentes-des-consommateurs-et-leur-impact-sur-les-strategies-dengagement-numerique-146868?utm\"> vorecol <\/a>: <\/p>\n\n\n\n<p>\u201c\u00c0 l&rsquo;\u00e8re num\u00e9rique, les consommateurs se transforment rapidement\u201d<\/p>\n\n\n\n<p><strong>Pourquoi j\u2019ai choisi ce sujet ?&nbsp;<\/strong><\/p>\n\n\n\n<p>Simple curiosit\u00e9 en voyant un article qui parle d\u2019\u00e9tudiants !&nbsp;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe Les Echos \u2013 Le Parisien M\u00e9dias affirme son engagement aupr\u00e8s de la nouvelle g\u00e9n\u00e9ration en cultivant son int\u00e9r\u00eat pour les secteurs des m\u00e9dias, [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-419","post","type-post","status-publish","format-standard","hentry","category-veille"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/posts\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/comments?post=419"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/posts\/419\/revisions"}],"predecessor-version":[{"id":421,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/posts\/419\/revisions\/421"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/categories?post=419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/wp-json\/wp\/v2\/tags?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}