{"id":8,"name":"clarahnf","url":"","description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/author\/clarahnf\/","slug":"clarahnf","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7a13fb59d44c1bebc6cef947151c83f6c18fcd10df8e5fe7136af769b51b80ac?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7a13fb59d44c1bebc6cef947151c83f6c18fcd10df8e5fe7136af769b51b80ac?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7a13fb59d44c1bebc6cef947151c83f6c18fcd10df8e5fe7136af769b51b80ac?s=96&d=mm&r=g"},"meta":[],"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/users\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/users"}]}}