{"id":5522,"date":"2026-03-31T15:16:06","date_gmt":"2026-03-31T13:16:06","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/lsempere\/?p=614"},"modified":"2026-03-31T15:16:06","modified_gmt":"2026-03-31T13:16:06","slug":"feu-chatterton-le-phenomene-incontournable-des-festivals-en-2026","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/2026\/03\/31\/feu-chatterton-le-phenomene-incontournable-des-festivals-en-2026\/","title":{"rendered":"Feu! Chatterton : le ph\u00e9nom\u00e8ne incontournable des festivals en 2026"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/presse.louvre.fr\/wp-content\/uploads\/2023\/02\/1675439824_feu-chatterton-au-louvre-009-c-muse-du-louvre-olivier-ouadah-1500x984.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Feu! Chatterton en r\u00e9sidence au Louvre CREDIT : louvre.fr<\/figcaption><\/figure>\n\n\n\n<p>Feu! Chatterton est devenu, en quelques ann\u00e9es, le groupe incontournable du rock fran\u00e7ais. Port\u00e9 par la voix unique d&rsquo;Arthur Teboul et une \u00e9nergie d\u00e9bordante, ce quintette parisien r\u00e9ussit le pari de m\u00e9langer la po\u00e9sie classique avec des sons modernes. Des bancs du lyc\u00e9e aux plus grandes sc\u00e8nes de festivals en 2026, retour sur le parcours exceptionnel de ces artistes qui ont su redonner du souffle \u00e0 la chanson fran\u00e7aise.<\/p>\n\n\n\n<p>Feu! Chatterton est un groupe de cinq musiciens parisiens. Il est men\u00e9 par le chanteur <strong>Arthur Teboul<\/strong>, connu pour sa voix grave et ses textes po\u00e9tiques. Autour de lui, on trouve <strong>Cl\u00e9ment Doumic<\/strong> et <strong>S\u00e9bastien Wolf<\/strong> aux guitares et aux claviers, ainsi qu&rsquo;<strong>Antoine Wilson<\/strong> \u00e0 la basse et <strong>Rapha\u00ebl de Pressigny<\/strong> \u00e0 la batterie. Ensemble, ils m\u00e9langent la chanson fran\u00e7aise avec du rock moderne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un succ\u00e8s n\u00e9 d&rsquo;une bande d&rsquo;amis<\/h3>\n\n\n\n<p>Le groupe a commenc\u00e9 simplement avec des copains de lyc\u00e9e \u00e0 Paris qui aimaient la po\u00e9sie et la musique. Leur carri\u00e8re a vraiment d\u00e9coll\u00e9 en 2014 avec la chanson <em>La Malinche<\/em>, qui est devenue un tube \u00e0 la radio. Depuis, ils ont sorti trois albums qui ont tr\u00e8s bien march\u00e9 et ils remplissent de grandes salles de concert partout en France. Le chanteur <strong>(A. Teboul)<\/strong>, est aussi devenu connu pour ses livres de po\u00e8mes et ses apparitions au cin\u00e9ma.<\/p>\n\n\n\n<div style=\"text-align: center;\">\n  <iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/wBB_gLKEa5c?si=yvwrRE00s9fH2XFo\" frameborder=\"0\" allowfullscreen><\/iframe>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Un m\u00e9lange de chansons et de rock<\/h3>\n\n\n\n<p>Leur style musical est un m\u00e9lange entre la <strong>chanson fran\u00e7aise<\/strong> classique et le <strong>rock<\/strong> moderne. Ils accordent beaucoup d&rsquo;importance aux paroles, un peu comme les anciens chanteurs c\u00e9l\u00e8bres, mais ils ajoutent des sons de guitares \u00e9lectriques et de synth\u00e9tiseurs. Passant de musiques calmes et douces, elles deviennent tr\u00e8s puissantes et rythm\u00e9es. C&rsquo;est ce m\u00e9lange original qui fait que l&rsquo;on reconna\u00eet le groupe d\u00e8s les premi\u00e8res notes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un parcours marqu\u00e9 par de grands albums et des projets vari\u00e9s <\/h3>\n\n\n\n<p>Depuis leurs d\u00e9buts, Feu! Chatterton a sorti trois albums studio qui ont chacun marqu\u00e9 la musique fran\u00e7aise. Leur premier disque, <strong>\u00ab\u00a0Ici le jour (a tout enseveli)\u00a0\u00bb<\/strong> (2015), a pos\u00e9 les bases de leur style po\u00e9tique. Le deuxi\u00e8me, <strong>\u00ab\u00a0L&rsquo;Oiseleur\u00a0\u00bb<\/strong> (2018), a confirm\u00e9 leur talent avec des chansons plus amples. Enfin, <strong>\u00ab\u00a0Palais d&rsquo;argile\u00a0\u00bb<\/strong> (2021), produit avec le musicien \u00e9lectro <strong>Arnaud Rebotini<\/strong>, a \u00e9t\u00e9 un immense succ\u00e8s populaire gr\u00e2ce au tube <em><a href=\"https:\/\/youtu.be\/55SwKPVMVM4?list=RD55SwKPVMVM4\">Monde Nouveau<\/a><\/em>. Au-del\u00e0 de leurs disques, ils ont collabor\u00e9 avec des artistes vari\u00e9s comme le chanteur <strong>Christophe<\/strong> ou le rappeur <strong>Prince Waly<\/strong>, et ont m\u00eame compos\u00e9 la musique du film <em>La Grande Magie<\/em> en 2023.<\/p>\n\n\n\n<div style=\"display: flex; justify-content: center;\">\n  <iframe data-testid=\"embed-iframe\" style=\"border-radius:12px; max-width: 500px;\" src=\"https:\/\/open.spotify.com\/embed\/artist\/538TfjnJpRXI80MHYWfKlo?utm_source=generator\" width=\"100%\" height=\"352\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Des r\u00e9compenses qui saluent leur succ\u00e8s<\/h3>\n\n\n\n<p> Le groupe a \u00e9t\u00e9 tr\u00e8s vite reconnu par les professionnels et le public. D\u00e8s 2014, ils remportent des prix prestigieux pour les jeunes talents, comme le <strong>Prix F\u00e9lix-Leclerc<\/strong>. Leurs albums ont re\u00e7u des certifications importantes : ils sont <strong>disques d&rsquo;or<\/strong> et m\u00eame <strong>disque de platine<\/strong> pour leur troisi\u00e8me opus. Ils sont \u00e9galement des habitu\u00e9s des <strong>Victoires de la Musique<\/strong>, o\u00f9 ils ont re\u00e7u plusieurs nominations dans les cat\u00e9gories reines comme \u00ab\u00a0Artiste masculin de l&rsquo;ann\u00e9e\u00a0\u00bb, \u00ab\u00a0Meilleur album\u00a0\u00bb et \u00ab\u00a0Chanson originale\u00a0\u00bb. Cette reconnaissance montre qu&rsquo;ils font d\u00e9sormais partie des piliers de la sc\u00e8ne fran\u00e7aise actuelle.<\/p>\n\n\n\n<p>Feu! Chatterton a ainsi donc su transformer une simple amiti\u00e9 de jeunesse en une carri\u00e8re exemplaire, marqu\u00e9e par des albums cultes et des r\u00e9compenses prestigieuses. Que ce soit \u00e0 travers leurs textes travaill\u00e9s ou leurs musiques puissantes, ils ont impos\u00e9 un style reconnaissable entre tous. Aujourd&rsquo;hui consid\u00e9r\u00e9s comme des artistes majeurs de notre paysage musical, ils continuent de surprendre leur public et de prouver que le rock et la po\u00e9sie font toujours bon m\u00e9nage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feu! Chatterton est devenu, en quelques ann\u00e9es, le groupe incontournable du rock fran\u00e7ais. Port\u00e9 par la voix unique d&rsquo;Arthur Teboul et une \u00e9nergie d\u00e9bordante, ce [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,12],"tags":[8,9,11],"class_list":["post-5522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","category-pop-francaise-musique","tag-8","tag-festival","tag-musique"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/posts\/5522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/comments?post=5522"}],"version-history":[{"count":0,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/posts\/5522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/media?parent=5522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/categories?post=5522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/wp-json\/wp\/v2\/tags?post=5522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}