{"id":92,"date":"2024-10-11T16:59:44","date_gmt":"2024-10-11T14:59:44","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/?p=92"},"modified":"2024-10-15T19:24:05","modified_gmt":"2024-10-15T17:24:05","slug":"lusurpation-didentite","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/2024\/10\/11\/lusurpation-didentite\/","title":{"rendered":"L&rsquo;usurpation d&rsquo;identit\u00e9"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.banque-france.fr\/fr\/a-votre-service\/particuliers\/agir-usurpation-identite#:~:text=Une%20usurpation%20d'identit\u00e9%2C%20c,agit%20d'un%20d\u00e9lit%20p\u00e9nal.\" data-type=\"link\" data-id=\"https:\/\/www.banque-france.fr\/fr\/a-votre-service\/particuliers\/agir-usurpation-identite#:~:text=Une%20usurpation%20d'identit\u00e9%2C%20c,agit%20d'un%20d\u00e9lit%20p\u00e9nal.\">Selon la banque de France<\/a> une usurpation d&rsquo;identit\u00e9, c&rsquo;est&nbsp;<strong>lorsqu&rsquo;une personne se fait passer pour vous, utilise vos donn\u00e9es personnelles sans votre accord et r\u00e9alise diff\u00e9rents actes en votre nom<\/strong>.<\/p>\n\n\n\n<p>En France de nombreuses personnalit\u00e9 ( chanteurs, cr\u00e9ateur de contenue, acteurs) on une r\u00e9el influence sur de nombreuses personnes notamment les plus jeunes. En r\u00e8gle g\u00e9n\u00e9rale c&rsquo;est personnalit\u00e9s sont donc tr\u00e8s appr\u00e9ci\u00e9es des Fran\u00e7ais. Selon <a href=\"https:\/\/www.ifop.com\/publication\/le-top-50-des-personnalites-13\/\" data-type=\"link\" data-id=\"https:\/\/www.ifop.com\/publication\/le-top-50-des-personnalites-13\/\">Ifop<\/a>  voici la liste des personnalit\u00e9s Fran\u00e7aises les plus appr\u00e9ci\u00e9es en D\u00e9cembre 2023. <\/p>\n\n\n\n<p> 1- Jean Jacques Golman <\/p>\n\n\n\n<p>2- Florent Pagny<\/p>\n\n\n\n<p>3- Thomas Pesquet <\/p>\n\n\n\n<p>4- Omar Sy<\/p>\n\n\n\n<p>5- Vianney <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Certain de c&rsquo;est nom son aussi connue pour des raisons plus graves, Thomas Pesquet et Omar Sy apparaissent dans le top 10 des c\u00e9l\u00e9brit\u00e9s les plus exploit\u00e9es par les cybercriminels.  Voici le classement <a href=\"https:\/\/www.blogdumoderateur.com\/usurpation-identite-10-celebrites-utilisees-hackeurs-2024\/\" data-type=\"link\" data-id=\"https:\/\/www.blogdumoderateur.com\/usurpation-identite-10-celebrites-utilisees-hackeurs-2024\/\">du blog du mod\u00e9rateur<\/a> : <\/p>\n\n\n\n<p>1- Ang\u00e8le (chanteuse)<\/p>\n\n\n\n<p>2-Timoth\u00e9 Chalamet (acteur) <\/p>\n\n\n\n<p>3- Pierre Niney (acteur)<\/p>\n\n\n\n<p>4- Lena Mahfouf (cr\u00e9atrices de contenue)<\/p>\n\n\n\n<p>5- C\u00e9line Dion (chanteuse)<\/p>\n\n\n\n<p>6-Aya Nakamura (chanteuse)<\/p>\n\n\n\n<p>7-SCH  (chanteur)<\/p>\n\n\n\n<p>8-Squeezie (cr\u00e9ateur de contenue)<\/p>\n\n\n\n<p>9-Thomas Pesquet (astronaute)<\/p>\n\n\n\n<p>10-Omar Sy ( acteur)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Depuis plusieurs mois l&rsquo;IA est tr\u00e8s exploit\u00e9s et les cybercriminels ne s&rsquo;en pas m\u00e9content, gr\u00e2ce \u00e0 celle si ils peuvent rendre leurs arnaques encore plus cr\u00e9dible. Ils peuvent notamment organiser des faux concours dans le but d&rsquo;obtenir des informations personnelle (adresse, code de carte bancaire&#8230;) sur les victimes <\/p>\n\n\n\n<p>Mais l&rsquo;usurpation d&rsquo;identit\u00e9s est bien pr\u00e9sente dans le monde entier ,<a href=\"https:\/\/www.topito.com\/top-histoires-dingues-usurpation-identite\" data-type=\"link\" data-id=\"https:\/\/www.topito.com\/top-histoires-dingues-usurpation-identite\">Topito<\/a> \u00e0 r\u00e9unie dans un articles les histoires les plus folles d&rsquo;usurpation d&rsquo;identit\u00e9. Cela nous prouve bien que cette arnaque est tr\u00e8s d\u00e9velopp\u00e9e et pas seulement en France.<\/p>\n\n\n\n<p>Dans c&rsquo;est histoires on peut retrouver celle d&rsquo;une employ\u00e9e du service des fraudes Am\u00e9ricain ( Internal Revenue Service) qui \u00e0 profiter de son poste pour elle m\u00eame voler l&rsquo;identit\u00e9 de ses clients afin de leur voler de l&rsquo;argent. M\u00eame si l&#8217;employ\u00e9e \u00e0 \u00e9t\u00e9 punis pour ce qu&rsquo;elle \u00e0 fait ( condamn\u00e9e \u00e0 neuf ans de prison) cela donne une mauvaise image de marque \u00e0 l&rsquo;entreprise. <\/p>\n\n\n\n<p>L&rsquo;hiver approche \u00e0 grand pas et selon le site <a href=\"https:\/\/www.effy.fr\/magazine\/chauffage-au-bois-40-des-maisons-individuelles-en-france-en-sont-equipees\" data-type=\"link\" data-id=\"https:\/\/www.effy.fr\/magazine\/chauffage-au-bois-40-des-maisons-individuelles-en-france-en-sont-equipees\">Effy<\/a> en 2023 pr\u00e8s de 40% des m\u00e9nages Fran\u00e7ais \u00e9taient \u00e9quip\u00e9s du chauffage au bois. Cela repr\u00e9sente donc une grande partie de la population. C Le site <a href=\"https:\/\/www.boursorama.com\/patrimoine\/actualites\/bois-de-chauffage-des-escrocs-en-ligne-ont-usurpe-l-identite-d-une-vraie-entreprise-55a3d0b1e5665cac6a9f34d1dcaa0aa9\" data-type=\"link\" data-id=\"https:\/\/www.boursorama.com\/patrimoine\/actualites\/bois-de-chauffage-des-escrocs-en-ligne-ont-usurpe-l-identite-d-une-vraie-entreprise-55a3d0b1e5665cac6a9f34d1dcaa0aa9\">Boursorama<\/a>  nous fait pare de l&rsquo;histoire qui est arriv\u00e9 \u00e0 une entreprise de bois de chauffage. <\/p>\n\n\n\n<p>Des cybercriminels on usurp\u00e9 l&rsquo;identit\u00e9 de l&rsquo;entreprise en envoyant des factures tr\u00e8s \u00e9lev\u00e9 au clients de l&rsquo;entreprise, et en n&rsquo;envoyant jamais le bois command\u00e9. Suite \u00e0 cela les propri\u00e9taires de l&rsquo;entreprise on apporter un message au clients : ils ne vendent pas de bois en ligne, donc si les clients voit une annonce passer sur internet par rapport \u00e0 leur vente de bois cela est une arnaque. <\/p>\n\n\n\n<p>Encore une fois, l&rsquo;usurpation d&rsquo;identit\u00e9 peut facilement nuir \u00e0 l&rsquo;image de marque d&rsquo;une entreprise. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon la banque de France une usurpation d&rsquo;identit\u00e9, c&rsquo;est&nbsp;lorsqu&rsquo;une personne se fait passer pour vous, utilise vos donn\u00e9es personnelles sans votre accord et r\u00e9alise diff\u00e9rents actes en votre nom. En France de nombreuses personnalit\u00e9 ( chanteurs, cr\u00e9ateur de contenue, acteurs) on une r\u00e9el influence sur de nombreuses personnes notamment les plus jeunes. En r\u00e8gle g\u00e9n\u00e9rale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-92","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":7,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":101,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/92\/revisions\/101"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}