{"id":67,"date":"2024-10-08T15:14:43","date_gmt":"2024-10-08T13:14:43","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/?p=67"},"modified":"2024-10-11T09:02:11","modified_gmt":"2024-10-11T07:02:11","slug":"octobre-rose","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/2024\/10\/08\/octobre-rose\/","title":{"rendered":"Octobre rose"},"content":{"rendered":"\n<p> Le cancer du sein \u00e0 toucher 61 214 nouveaux cas en 2023. Il est plus r\u00e9pandu chez les femmes que chez les hommes. <\/p>\n\n\n\n<p>Aujourd&rsquo;hui beaucoup de monde est sensibiliser \u00e0 cette maladie c&rsquo;est en 1994 que la fameuse campagne d&rsquo;octobre rose est apparue en France, et en cet Octobre 2024, <a href=\"https:\/\/www.inoreader.com\/article\/3a9c6e744fd1b83f-octobre-rose-2024-5-actions-marketing-creatives\" data-type=\"link\" data-id=\"https:\/\/www.inoreader.com\/article\/3a9c6e744fd1b83f-octobre-rose-2024-5-actions-marketing-creatives\">5 actions marketing<\/a> on \u00e9t\u00e9 mise en place. Cet article est apparu en premier sur JUPDLC.<\/p>\n\n\n\n<p>Cela vas susciter les gens \u00e0 en parler autour d&rsquo;eux, notamment la campagne de CNP assurance qui au premeirs abords peut apporter de l&rsquo;indignation, mais qui au final \u00e0 un message tr\u00e8s touchant. Cela vas donc inciter les gens \u00e0 en parler autour d&rsquo;eux ( bouche \u00e0 oreille, r\u00e9seaux sociaux ) afin de pouvoir sensibiliser la populations sur les in\u00e9galit\u00e9s que subissent les personnes qui ont eu ou qui ont le cancer du sein. <a href=\"https:\/\/www.cnp.fr\/le-groupe-cnp-assurances\/newsroom\/communiques-de-presse\/2024\/pas-a-vendre-pour-octobre-rose-cnp-assurances-interpelle-le-grand-public-sur-les-difficultes-des-femmes-ayant-eu-un-cancer-du-sein-pour\" data-type=\"link\" data-id=\"https:\/\/www.cnp.fr\/le-groupe-cnp-assurances\/newsroom\/communiques-de-presse\/2024\/pas-a-vendre-pour-octobre-rose-cnp-assurances-interpelle-le-grand-public-sur-les-difficultes-des-femmes-ayant-eu-un-cancer-du-sein-pour\">Le site CNP <\/a>assurance \u00e0 lui m\u00eame mis en ligne sur son site cette campagne.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Quant \u00e0 la marque <a href=\"https:\/\/www.veepee.fr\/experiences\/octobre-rose1\/#\/\" data-type=\"link\" data-id=\"https:\/\/www.veepee.fr\/experiences\/octobre-rose1\/#\/\">Veepe<\/a> elle \u00e0 pr\u00e9f\u00e9rer faire sa campagne avec ses partenaires, \u00e0 partir du 18 octobre un grand nombre de marque pr\u00e9sente sur le site de Veepe comme Claudie Pierlot, Briston, Simone P\u00e9rel&#8230; \u00e0 chaque achat 1 euros est revers\u00e9 \u00e0 l&rsquo;association ruban rose. De plus ils ont mis en ligne des conseils pour d\u00e9pister le cancer du sein.<\/p>\n\n\n\n<p>D&rsquo;autre marques comme Courir et France Pare Brise mais aussi la Ligue contre le cancer, on toutes lancer des actions marketings pour \u00e9viter tout les tabous atour du cancer du sein et pour que les gens connaissent mieux ceux  cancer<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cancer du sein \u00e0 toucher 61 214 nouveaux cas en 2023. Il est plus r\u00e9pandu chez les femmes que chez les hommes. Aujourd&rsquo;hui beaucoup de monde est sensibiliser \u00e0 cette maladie c&rsquo;est en 1994 que la fameuse campagne d&rsquo;octobre rose est apparue en France, et en cet Octobre 2024, 5 actions marketing on \u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-67","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":6,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/67\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/posts\/67\/revisions\/74"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/categories?post=67"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliabriand\/wp-json\/wp\/v2\/tags?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}