{"id":402,"date":"2025-01-22T20:11:00","date_gmt":"2025-01-22T19:11:00","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/?p=402"},"modified":"2025-01-24T10:13:38","modified_gmt":"2025-01-24T09:13:38","slug":"tiktok-larme-secrete-de-trump-quand-le-president-danse-sur-lere-de-la-gen-z","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/2025\/01\/22\/tiktok-larme-secrete-de-trump-quand-le-president-danse-sur-lere-de-la-gen-z\/","title":{"rendered":"TikTok, l&rsquo;arme secr\u00e8te de Trump : Quand le pr\u00e9sident danse sur l&rsquo;\u00e8re de la Gen Z"},"content":{"rendered":"\n<p>Ce 20 janvier 2025, Donald Trump a entam\u00e9 son second mandat non cons\u00e9cutif en tant que 47\u00e8me pr\u00e9sident des \u00c9tats-Unis. Lors de son discours d&rsquo;investiture au Capitole, Trump a d\u00e9peint une vision contrast\u00e9e de l&rsquo;Am\u00e9rique, m\u00ealant critiques et promesses ambitieuses. Parmi ses promesses : \u00ab&nbsp;sauver TikTok&nbsp;\u00bb et ne pas appliquer les sanctions pr\u00e9vues par la loi adopt\u00e9e sous la pr\u00e9sidence Biden.<\/p>\n\n\n\n<p>En effet, le 24 avril 2024, Joe Biden a sign\u00e9 la loi \u00ab\u00a0Protecting Americans from Foreign Adversary Controlled Applications Act\u00a0\u00bb (PAFACA), visant \u00e0 prot\u00e9ger la s\u00e9curit\u00e9 nationale des \u00c9tats-Unis en emp\u00eachant la Chine d&rsquo;acc\u00e9der aux donn\u00e9es sensibles des utilisateurs am\u00e9ricains de TikTok.<\/p>\n\n\n\n<p>Une fois cette mesure prise, elle devait entrer en vigueur le 19 janvier 2025. Mais voil\u00e0 qu\u2019apr\u00e8s seulement 14h de suspension de TikTok sur le territoire am\u00e9ricain, l\u2019application a \u00e9tonnamment revu le jour.&nbsp;<\/p>\n\n\n\n<p>Mais pourquoi donc Trump a-t-il soudainement chang\u00e9 d\u2019avis ?&nbsp;<\/p>\n\n\n\n<p>Bien qu\u2019il affirmait en \u00e9t\u00e9 2020 que TikTok allait \u00eatre interdit, le pr\u00e9sident r\u00e9publicain a finalement opt\u00e9 pour offrir 90 jours de sursis \u00e0 la plateforme, qualifiant d\u00e9sormais TikTok de \u00ab&nbsp;moyen unique de promouvoir la libert\u00e9 d&rsquo;expression&nbsp;\u00bb.&nbsp;<\/p>\n\n\n\n<p>Et cela, il l\u2019admet \u00e9videmment depuis que son compte TikTok a gagn\u00e9 en popularit\u00e9, accumulant pr\u00e8s de 15&nbsp;millions de followers.&nbsp;<\/p>\n\n\n\n<p>Lors de sa campagne \u00e9lectorale, il semblerait que le pr\u00e9sident ait r\u00e9ussi \u00e0 attirer l\u2019attention des jeunes \u00e9lecteurs, souvent d\u00e9sint\u00e9ress\u00e9s par la politique. Cette strat\u00e9gie a r\u00e9ussi \u00e0 atteindre un groupe de personnes g\u00e9n\u00e9ralement difficile \u00e0 int\u00e9resser, tout en encourageant de mani\u00e8re implicite les jeunes \u00e0 participer \u00e0 la vie politique et citoyenne.<\/p>\n\n\n\n<p>Pour r\u00e9sumer, TikTok est devenu un outil strat\u00e9gique pour les personnalit\u00e9s politiques, leur permettant de s\u00e9duire l&rsquo;\u00e9lectorat jeune en adoptant ses codes de communication. Cependant, derri\u00e8re ces vid\u00e9os humoristiques et ces tendances se cache une strat\u00e9gie marketing calcul\u00e9e, qui ne refl\u00e8te pas n\u00e9cessairement un r\u00e9el engagement politique.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a href=\"https:\/\/jai-un-pote-dans-la.com\/trump-offre-90-jours-de-sursis-a-tiktok\" target=\"_blank\" rel=\"noopener\">https:\/\/jai-un-pote-dans-la.com\/trump-offre-90-jours-de-sursis-a-tiktok<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.lepoint.fr\/monde\/pourquoi-donald-trump-veut-absolument-sauver-tiktok-10-01-2025-2579629_24.php#11\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lepoint.fr\/monde\/pourquoi-donald-trump-veut-absolument-sauver-tiktok-10-01-2025-2579629_24.php#11<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.lemonde.fr\/international\/video\/2025\/01\/20\/investiture-de-donald-trump-les-images-de-la-ceremonie_6507641_3210.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lemonde.fr\/international\/video\/2025\/01\/20\/investiture-de-donald-trump-les-images-de-la-ceremonie_6507641_3210.html<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.iscom.fr\/actualite\/tiktok-le-nouveau-terrain-de-jeu-de-la-politique\" target=\"_blank\" rel=\"noopener\">https:\/\/www.iscom.fr\/actualite\/tiktok-le-nouveau-terrain-de-jeu-de-la-politique<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce 20 janvier 2025, Donald Trump a entam\u00e9 son second mandat non cons\u00e9cutif en tant que 47\u00e8me pr\u00e9sident des \u00c9tats-Unis. Lors de son discours d&rsquo;investiture &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-402","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/comments?post=402"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/402\/revisions"}],"predecessor-version":[{"id":403,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/402\/revisions\/403"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/media?parent=402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/categories?post=402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/tags?post=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}