{"id":32,"date":"2024-10-14T20:23:17","date_gmt":"2024-10-14T18:23:17","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/?p=32"},"modified":"2024-10-14T20:23:17","modified_gmt":"2024-10-14T18:23:17","slug":"verification-de-lage-un-defi-pour-lacces-aux-sites-pornographiques","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/2024\/10\/14\/verification-de-lage-un-defi-pour-lacces-aux-sites-pornographiques\/","title":{"rendered":"V\u00e9rification de l&rsquo;\u00e2ge : un d\u00e9fi pour l&rsquo;acc\u00e8s aux sites pornographiques"},"content":{"rendered":"\n<p>Pour la veille du jour, nous allons parler de la v\u00e9rification de l\u2019\u00e2ge sur les sites pornographiques.&nbsp;<\/p>\n\n\n\n<p>R\u00e9cemment, l\u2019Arcom (L\u2019Autorit\u00e9 de r\u00e9gulation de la communication audiovisuelle et num\u00e9rique) \u00e0 d\u00e9cider de s\u00e9vir l\u2019encadrement de la \u00ab&nbsp;fiabilit\u00e9 du contr\u00f4le de l\u2019\u00e2ge des utilisateurs&nbsp;\u00bb en mettant en place un dispositif de double anonymat pour les mineurs qui tenterait d\u2019acc\u00e9der a ces sites.&nbsp;<\/p>\n\n\n\n<p>La probl\u00e9matique \u00e9tant que les sites pornographiques doivent r\u00e9pondre \u00e0 des exigences techniques pour bloquer leur acc\u00e8s aux mineurs tout en respectant leur vie priv\u00e9e.&nbsp;<\/p>\n\n\n\n<p>J\u2019ai choisi de d\u00e9velopper sur ce sujet car je trouve que la pr\u00e9vention autour des sites pornographiques et de leurs cons\u00e9quences n\u00e9fastes n\u2019est pas assez mis en avant dans les m\u00e9dias. Par ailleurs, j\u2019ai pu apprendre dans cet article que selon l\u2019institution Cnil (La Commission nationale de l\u2019informatique et des libert\u00e9s), 2,3 millions de mineurs fr\u00e9quentent des sites pornographiques en France.<\/p>\n\n\n\n<p>Ici, les th\u00e8mes abord\u00e9s sont la pornographie, mais surtout la s\u00e9curit\u00e9 des donn\u00e9es et des jeunes. Mais certaines probl\u00e9matiques s\u2019offrent \u00e0 nous: la mesure de double anonymat sera-t-elle vraiment efficace ?&nbsp;<\/p>\n\n\n\n<p>D\u2019apr\u00e8s un article de <em><a href=\"https:\/\/www.laprovence.com\/article\/societe\/7041635468119914\/une-carte-bancaire-pour-acceder-aux-sites-porno-larcom-devoile-ses-mesures-concretes-pour-proteger-les-mineurs\" target=\"_blank\" rel=\"noopener\">La Provence<\/a>, <\/em>utiliser temporairement la carte bancaire comme moyen de v\u00e9rifier l&rsquo;\u00e2ge de ses utilisateurs pourrait \u00eatre une solution\u00a0<\/p>\n\n\n\n<p>Et quelles sanctions sont pr\u00e9vues pour les plateformes qui ne respectent pas ces r\u00e8gles ?<\/p>\n\n\n\n<p>On retrouve directement sur le site du <a href=\"https:\/\/www.cnil.fr\/fr\/definition\/sanction#:~:text=formation restreinte peut :-,prononcer un rappel \u00e0 l&#039;ordre ;,maximal de 20 000 \u20ac.\" target=\"_blank\" rel=\"noopener\">Cnil<\/a> les sanctions pr\u00e9vues pour ceux qui n\u2019appliqueraient pas la loi. Pour en faire un r\u00e9sum\u00e9, le montant des sanctions p\u00e9cuniaires peut s\u2019\u00e9lever jusqu\u2019\u00e0 20 millions d\u2019euros ou dans le cas d\u2019une entreprise jusqu\u2019\u00e0 4 % du chiffre d\u2019affaires annuel mondial.<\/p>\n\n\n\n<p>Lien de l&rsquo;article: <a href=\"https:\/\/fr.themedialeader.com\/verification-de-lage-sur-les-sites-porno-larcom-impose-le-double-anonymat\/\" target=\"_blank\" rel=\"noopener\">https:\/\/fr.themedialeader.com\/verification-de-lage-sur-les-sites-porno-larcom-impose-le-double-anonymat\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la veille du jour, nous allons parler de la v\u00e9rification de l\u2019\u00e2ge sur les sites pornographiques.&nbsp; R\u00e9cemment, l\u2019Arcom (L\u2019Autorit\u00e9 de r\u00e9gulation de la communication &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"predecessor-version":[{"id":33,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts\/32\/revisions\/33"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}