{"id":24,"count":1,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/category\/reggae\/dub\/","name":"DUB","slug":"dub","taxonomy":"category","parent":23,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/categories\/23"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/jfremond\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}