{"id":1,"date":"2025-10-03T10:59:56","date_gmt":"2025-10-03T08:59:56","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/?p=1"},"modified":"2025-10-03T10:59:56","modified_gmt":"2025-10-03T08:59:56","slug":"bonjour-tout-le-monde","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/2025\/10\/03\/bonjour-tout-le-monde\/","title":{"rendered":"Bonjour tout le monde\u00a0!"},"content":{"rendered":"\n<p>Bienvenue sur WordPress. Ceci est votre premier article. Modifiez-le ou supprimez-le, puis commencez \u00e0 \u00e9crire\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur WordPress. Ceci est votre premier article. Modifiez-le ou supprimez-le, puis commencez \u00e0 \u00e9crire\u00a0!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/ebrehelin\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}