{"id":359,"date":"2026-01-23T20:16:13","date_gmt":"2026-01-23T19:16:13","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/?p=359"},"modified":"2026-01-23T20:16:31","modified_gmt":"2026-01-23T19:16:31","slug":"trop-cest-trop","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/2026\/01\/23\/trop-cest-trop\/","title":{"rendered":"Trop c&rsquo;est trop?"},"content":{"rendered":"\n<p><strong>\u00ab\u00a0C&rsquo;est trop?\u00a0\u00bb Telle est la traduction du nom de cette campagne lanc\u00e9e par le syndicat (et lobby) des producteurs de plastiques. Elle vise \u00e0 d\u00e9fendre l&rsquo;utilisation des plastiques en tant qu&#8217;emballage via une prise de cosnciebce sous laquelle se cache de la moquerie. Decryptage.<\/strong><\/p>\n\n\n\n<p>  Le remplacement des emballages plastiques par des emballages jug\u00e9s plus vertueux n\u2019a pas le vent en poupe ces temps-ci. En f\u00e9vrier dernier, l\u2019interdiction des emballages plastiques autour des fruits et l\u00e9gumes \u00e9tait report\u00e9e \u00e0 2030, \u00e0 la grande joie des lobbys du plastique, selon le m\u00e9dia <a href=\"https:\/\/reporterre.net\/Les-lobbies-du-plastique-retardent-la-fin-des-emballages-sur-les-legumes\">Reporterre<\/a>. Un an plus tard, le lobby du plastique <a href=\"https:\/\/www.polyvia.fr\/fr\">Polyvia<\/a> tente de redorer l\u2019image du plastique en tant qu\u2019emballage en lan\u00e7ant la campagne \u00ab\u00a0Too much\u00a0?\u00a0\u00bb, qui vise \u00e0 \u00ab\u00a0interroger les choix actuels en mati\u00e8re d\u2019emballages et, en particulier, la tendance \u00e0 remplacer le plastique par d\u2019autres mat\u00e9riaux\u00a0\u00bb, selon les d\u00e9clarations de Polyvia au journal <a href=\"https:\/\/www.lemonde.fr\/planete\/article\/2026\/01\/21\/la-campagne-too-much-du-lobby-de-la-plasturgie-pour-rehabiliter-les-emballages-plastiques_6663450_3244.html\">Le Monde<\/a>. \u00ab\u00a0C\u2019est absurde. Et c\u2019est volontaire.\u00a0\u00bb <a href=\"https:\/\/www.la-croix.com\/economie\/too-much-la-campagne-de-defense-des-emballages-plastique-fait-polemique-20260121\">explique<\/a> le syndicat national des industriels de la plasturgie et des composites\u00a0(nom complet de Polyvia). Le groupe indique que le chiffre d\u2019affaires des industriels su textile aurait recul\u00e9 de 4% en 2025. Ces chiffres seraient donc la base de cette campagne visant \u00e0 faire \u00e0 nouveau tourner le regard vers les emballages plastiques et donc continuer \u00e0 faire fonctionner les industries textiles. <\/p>\n\n\n\n<p>  \u00ab\u00a0Absurde\u00a0\u00bb peut \u00eatre le mot juste au sujet de cette campagne, diffus\u00e9e dans plus de 200 supermarch\u00e9s de grandes villes fran\u00e7aises et pr\u00e9vue pour <a href=\"https:\/\/partenaire-entreprise.com\/too-much-la-campagne-du-lobby-de-la-plasturgie-pour-redorer-le-blason-des-emballages-plastiques\/\">durer un an<\/a>. On y voit des emballages fait en mat\u00e9riaux autres que le plastique et jug\u00e9s \u00ab\u00a0illogiques\u00a0\u00bb par l\u2019entreprise pour les produits qu\u2019ils renferment, avec en-dessous de l\u2019image le slogan \u00ab\u00a0Les emballages plastiques\u00a0: pas syst\u00e9matiques, mais souvent logiques.\u00a0\u00bb On y voit par exemple un yaourt dans un pot en poils, ou encore de l\u2019essence dans un jerrican en papier mach\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"360\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-content\/uploads\/2026\/01\/Polyvia-1024x683.jpg\" alt=\"\" class=\"wp-image-360\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-content\/uploads\/2026\/01\/Polyvia-1024x683.jpg 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-content\/uploads\/2026\/01\/Polyvia-300x200.jpg 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-content\/uploads\/2026\/01\/Polyvia-768x512.jpg 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-content\/uploads\/2026\/01\/Polyvia.avif 1464w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.usinenouvelle.com\/emballage\/avec-la-campagne-too-much-les-plasturgistes-interrogent-les-choix-en-matiere-demballages.MWLXKBUDJVGJTIH5VI3MMKXXUM.html\">https:\/\/www.usinenouvelle.com\/emballage\/avec-la-campagne-too-much-les-plasturgistes-interrogent-les-choix-en-matiere-demballages.MWLXKBUDJVGJTIH5VI3MMKXXUM.html<\/a><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>  Sur son compte <a href=\"https:\/\/www.linkedin.com\/posts\/polyvia_too-much-activity-7416396024455270400-evjn\/?originalSubdomain=fr\">LinkedIn<\/a>, Polyvia affirme que la campagne \u00ab\u00a0Too much\u00a0?\u00a0\u00bb \u00ab\u00a0s\u2019inscrit dans une d\u00e9marche de transparence et de p\u00e9dagogie\u00a0\u00bb, et invite chacun \u00e0 \u00ab\u00a0ouvrir le dialogue pour replacer chaque mat\u00e9riau \u00e0 sa juste place, y compris le plastique, lorsque cela fait sens.\u00a0\u00bb. Donc de ne pas diaboliser le plastique.<\/p>\n\n\n\n<p>  Une \u00ab\u00a0<a href=\"https:\/\/www.les-emballages-plastiques.fr\/\">fiche p\u00e9dagogique\u00a0<\/a>\u00bb est m\u00eame accessible via le QR Code plac\u00e9 en bas des affiches. Le lobby y vente le c\u00f4t\u00e9 hygi\u00e9nique des emballages plastiques (qui sont selon elle pens\u00e9s pour \u00eatre recyclables dans chaque \u00e9tape de la fabrication) et propose aux internautes de \u00ab\u00a0change[r] de regard, ensemble\u00a0\u00bb sur l\u2019usage du plastique. Le ton est assez amical, l\u2019internaute est tutoy\u00e9, comme s\u2019il allait faire une grande d\u00e9couverte et comprendre la r\u00e9alit\u00e9. Du c\u00f4t\u00e9 absurde des emballages repr\u00e9sent\u00e9s au ton de la page internet d\u00e9di\u00e9e \u00e0 cette campagne, tout est fait pour attirer le public et mettre en avant \u00ab\u00a0une fili\u00e8re qui innove, qui repense ses pratiques et qui cherche \u00e0 concilier efficacit\u00e9, sobri\u00e9t\u00e9 et respect de l\u2019environnement\u00a0\u00bb.<\/p>\n\n\n\n<p>  Selon le magazine <a href=\"https:\/\/www.usinenouvelle.com\/article\/emballages-plastique-une-etude-pour-accelerer-la-transition-environnementale.N2238758\">Usine Nouvelle<\/a> (un m\u00e9dia en ligne sp\u00e9cialis\u00e9 dans les informations sur les industries), la campagne se base sur une \u00e9tude confi\u00e9e par Polyvia au cabinet de conseil en entreprises <a href=\"https:\/\/quantis.com\/fr\/\">Quantis<\/a>. La conclusion, selon Polyvia, est que tous les emballages ont leur propre impact environnemental, et que le plastique n\u2019est donc pas \u00e0 rejeter compl\u00e8tement.<\/p>\n\n\n\n<p><strong>\u00ab\u00a0Cette campagne est innapropri\u00e9e\u00a0\u00bb<\/strong><\/p>\n\n\n\n<p>Mais cette campagne n\u2019est pas du gout de tout le monde. Le ministre d\u00e9l\u00e9gu\u00e9 \u00e0 la transition \u00e9cologique Mathieu Lef\u00e8vre explique aupr\u00e8s du journal <a href=\"https:\/\/www.lemonde.fr\/planete\/article\/2026\/01\/21\/la-campagne-too-much-du-lobby-de-la-plasturgie-pour-rehabiliter-les-emballages-plastiques_6663450_3244.html\">Le Monde<\/a> que \u00ab cette campagne est inappropri\u00e9e face au d\u00e9fi plastique qui reste devant nous. Elle pr\u00e9sente de mani\u00e8re caricaturale l\u2019action publique (&#8230;)&nbsp;\u00bb En outre, selon ce m\u00eame m\u00e9dia, les extractions d\u2019\u00e9nergies fossiles n\u00e9cessaires \u00e0 la cr\u00e9ation du plastique ne sont pas prises en compte dans les calculs de gaz \u00e0 effet de serre. Ce qui n\u2019est pas pris en compte, \u00e9galement, ce sont \u00ab les impacts des micro- et des nanoplastiques, qui, contrairement au carton ou au papier (\u2026), sont retrouv\u00e9s dans les endroits les plus prot\u00e9g\u00e9s du monde et de nos corps (\u2026) et perturbent le bon fonctionnement du monde vivant&nbsp;\u00bb, explique la directrice de recherche \u00e0 l\u2019Institut national de recherche pour l\u2019agriculture, l\u2019alimentation et l\u2019environnement Nathalie Gontard.<\/p>\n\n\n\n<p>Sous <a href=\"https:\/\/www.facebook.com\/profile\/100064539140308\/search\/?q=too%20much\">la publication Facebook de l\u2019article du Monde<\/a>, des internautes outr\u00e9s par cette campagne \u00e9crivent des commentaires tels que \u00ab&nbsp;Le tout en usant des superbes IA g\u00e9n\u00e9rative&#8230; Un vrai \u00e9chec de bout en bout pour la plan\u00e8te.&nbsp;\u00bb ou encore \u00ab&nbsp;[Grandes surfaces] merci de veiller \u00e0 la protection des consommateurs et de ne pas relayer ce genre de communication d&rsquo;un autre temps. 2026 est l&rsquo;\u00e8re du r\u00e9emploi, [\u2026] fini l&rsquo;\u00e8re du jetable.&nbsp;\u00bb Il en est de m\u00eame sous le post LinkedIn de Polyvia&nbsp;: \u00ab&nbsp;le plastique est une solution dans certains usages. Mais le d\u00e9fendre en caricaturant ou en discr\u00e9ditant des alternatives rel\u00e8ve davantage de la mauvaise communication que de la p\u00e9dagogie.&nbsp;\u00bb. L\u2019entreprise continue \u00e0 se d\u00e9fendre de toutes moqueries en donnant simplement l\u2019argument d\u2019une prise de conscience essentielle. Affaire \u00e0 suivre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi ais-je choisi ce sujet???<\/h2>\n\n\n\n<p>   J\u2019ai choisi de faire un article sur cette campagne car elle m\u2019a outr\u00e9e d\u00e8s que je l\u2019ai vue. En effet, en tant que militante \u00e9cologiste, j\u2019ai trop souvent remarqu\u00e9 que les \u00e9cologistes et les personnes faisant des actions pour l\u2019environnement sont discr\u00e9dit\u00e9s au moindre mot et \u00e0 la moindre action, \u00e0 l\u2019\u00e9chelle locale comme nationale. Par exemple, je faisais partie d\u2019une association de lutte contre un puit d\u2019extraction d\u2019\u00e9nergies fossiles en Lorraine. Un jour quelqu\u2019un nous avait demand\u00e9 \u00e0 ce sujet \u00ab\u00a0vous voulez revenir \u00e0 la bougie\u00a0?\u00a0\u00bb. Non, et chaque id\u00e9e ou action \u00e9cologiste n\u2019est pas extr\u00e9miste ou absurde \u00e0 ce point. Elle est faite pour construire un monde durable pour aujourd\u2019hui et demain. Mais pas via les extr\u00eames mis en avant par Polyvia\u00a0: jamais personne n\u2019a parl\u00e9 de faire des jerricans en papier et des pots de yaourt en poils\u00a0! Je trouve cette campagne moqueuse et discr\u00e9ditante envers les actions \u00e9cologiques. La deuxi\u00e8me raison pour laquelle j\u2019ai choisi de parler de cette campagne est qu\u2019elle est passionnante d\u2019un point de vue communicationnel\u00a0: elle est ironique, mais \u00e9galement r\u00e9alis\u00e9e par l\u2019un des plus gros lobbies du plastique en France, ce qui n\u2019est pas sans cons\u00e9quences puisque les lobbies sont l\u00e0 pour d\u00e9fendre les int\u00e9r\u00eats de leurs partenaires par tous les moyens. Et c\u2019est de la communication.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0C&rsquo;est trop?\u00a0\u00bb Telle est la traduction du nom de cette campagne lanc\u00e9e par le syndicat (et lobby) des producteurs de plastiques. Elle vise \u00e0 d\u00e9fendre l&rsquo;utilisation des plastiques en tant qu&#8217;emballage via une prise de cosnciebce sous laquelle se cache de la moquerie. Decryptage. Le remplacement des emballages plastiques par des emballages jug\u00e9s plus vertueux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-359","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":2,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":362,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/posts\/359\/revisions\/362"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/danamuller\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}