{"id":32,"date":"2024-10-16T21:53:49","date_gmt":"2024-10-16T19:53:49","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/?p=32"},"modified":"2024-10-16T21:54:16","modified_gmt":"2024-10-16T19:54:16","slug":"quelle-campagne-choisir-pour-octobre-rose","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/2024\/10\/16\/quelle-campagne-choisir-pour-octobre-rose\/","title":{"rendered":"Quelle campagne pour Octobre Rose ?"},"content":{"rendered":"\n<p>Le mois d\u2019octobre est bien souvent significatif du retour de l\u2019automne, d\u2019Halloween, et de l\u2019hiver qui arrive. Mais si on s\u2019y penche davantage, le mois d\u2019octobre c\u2019est aussi un mois de lutte : la lutte contre le cancer du sein. Ainsi, cet article porte sur les \u201cmeilleures campagnes pour Octobre Rose 2024\u201d. Publi\u00e9 le 10 octobre 2024 sur le site de <a href=\"https:\/\/lareclame.fr\/octobre-rose-2024-top-4-association-304834\" data-type=\"link\" data-id=\"https:\/\/lareclame.fr\/octobre-rose-2024-top-4-association-304834\">La R\u00e9clame<\/a>, il est \u00e9crit par Iris M.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p>Pourquoi cet article ? Comme vu pr\u00e9c\u00e9demment, le mois d\u2019octobre est un moment de l\u2019ann\u00e9e r\u00e9serv\u00e9 pour une campagne nationale tourn\u00e9e autour de la sensibilisation au d\u00e9pistage du cancer du sein pour les femmes ainsi qu\u2019\u00e0 la r\u00e9colte de fonds pour la recherche de de cette maladie. De ce fait, l&rsquo;article rejoint ici deux th\u00e8mes centraux : la cause du cancer et la fa\u00e7on dont cette campagne est communiqu\u00e9e. C\u2019est ce qui fait selon moi tout l\u2019attrait de cet article. Int\u00e9ressons nous alors \u00e0 ces campagnes\u2026<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"563\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-1024x563.jpeg\" alt=\"\" class=\"wp-image-35\" style=\"width:1133px;height:auto\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-1024x563.jpeg 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-300x165.jpeg 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-2000x1100.jpeg 2000w, https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-1536x845.jpeg 1536w, https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2024\/10\/AdobeStock_453903876-scaled-3-2048x1126.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Image tir\u00e9e du site Grand Paris Sud.<\/figcaption><\/figure>\n\n\n\n<p>Iris M, nous expose ici 4 grandes campagnes :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La premi\u00e8re est r\u00e9alis\u00e9e par l\u2019agence de communication \u201cThe Good Company\u201d pour \u201cCNP Assurances\u201d. CNP Assurances affiche ici des panneaux sur lesquels il est inscrit <em>\u201cPas \u00e0 vendre aux femmes ayant eu un cancer du sein\u201d<\/em>. Elle d\u00e9nonce d\u00e8s lors les difficult\u00e9s auxquelles peuvent faire face les femmes atteintes de cette maladie lors de l&rsquo;achat d\u2019un bien immobilier. En effet, ces derni\u00e8res ne peuvent avoir acc\u00e8s \u00e0 une assurance emprunteur avant la fin de leur protocole th\u00e9rapeutique. Si elles en ont l\u2019acc\u00e8s, les tarifs sont bien plus \u00e9lev\u00e9s. Le cancer du sein est consid\u00e9r\u00e9 pour beaucoup d\u2019assurances comme un risque aggrav\u00e9 de sant\u00e9. Ainsi, c\u2019est ce que veut contrer CNP Assurances par cette campagne.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La deuxi\u00e8me est \u00e0 l&rsquo;initiative de la Ligue contre le cancer et DDB (une agence de communication). Leur but ici : mettre en avant la sororit\u00e9. Elles soutiennent ici une campagne encourageant la solidarit\u00e9 entre femmes. Ainsi, l\u2019int\u00e9gralit\u00e9 de leur campagne est disponible sur le site de<a href=\"https:\/\/www.ligue-cancer.net\/octobre-rose\" data-type=\"link\" data-id=\"https:\/\/www.ligue-cancer.net\/octobre-rose\"> la Ligue contre le cancer<\/a>.\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En troisi\u00e8me position, on retrouve Veepee, une entreprise fran\u00e7aise de commerce \u00e9lectronique qui nous pr\u00e9sente ici son #Boobscodes. La campagne est en collaboration avec diff\u00e9rentes associations qui sensibilisent et financent des projets de recherche pour lutter contre cette maladie (telle que \u201cRuban Rose\u201d). Selon l\u2019article, \u201cchaque marque participant \u00e0 l\u2019op\u00e9ration reverse 1\u20ac par commande valid\u00e9e \u00e0 ces associations, contribuant ainsi au financement de la recherche et \u00e0 la sensibilisation\u201d. L\u2019ann\u00e9e derni\u00e8re, l\u2019op\u00e9ration \u00e0 permis de r\u00e9colter 265 000 \u20ac ! Ce genre de recherches sont approfondies dans des laboratoires tels que <a href=\"https:\/\/curie.fr\/la-recherche-sur-le-cancer-du-sein\">l\u2019Institut Curie<\/a>, sp\u00e9cialis\u00e9 dans la recherche du cancer en g\u00e9n\u00e9ral et plus particuli\u00e8rement du cancer du sein. Il est int\u00e9ressant d\u2019y retrouver leurs objets d\u2019\u00e9tudes et les avanc\u00e9es de leurs exp\u00e9riences.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Enfin, on retrouve le spectacle chor\u00e9graphi\u00e9 de l\u2019association Ruban Rose \u00e0 Paris sur la place Vend\u00f4me. Elle repr\u00e9sentait le d\u00e9but d\u2019octobre rose avec notamment de nombreux monuments historiques tels que La Tour Eiffel, \u00e9clair\u00e9s en rose pour l\u2019occasion !<\/li>\n<\/ul>\n\n\n\n<p>Apr\u00e8s avoir analys\u00e9 ces campagnes, il est pertinent de constater qu&rsquo;au-del\u00e0 de l&rsquo;engagement de structures priv\u00e9es ou d\u2019associations solidaires comme on vient de le voir, ces campagnes sont aussi relay\u00e9es par des structures publiques. Notamment le site de <a href=\"https:\/\/www.service-public.fr\/particuliers\/actualites\/A15216\" data-type=\"link\" data-id=\"https:\/\/www.service-public.fr\/particuliers\/actualites\/A15216\">service-public.fr<\/a>, a publi\u00e9 le 1er octobre un article qui incite \u00e0 se faire d\u00e9pister. On y retrouve le dispositif du d\u00e9pistage mais \u00e9galement diverses informations \u00e0 ce sujet.\u00a0<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mois d\u2019octobre est bien souvent significatif du retour de l\u2019automne, d\u2019Halloween, et de l\u2019hiver qui arrive. Mais si on s\u2019y penche davantage, le mois d\u2019octobre c\u2019est aussi un mois de lutte : la lutte contre le cancer du sein. Ainsi, cet article porte sur les \u201cmeilleures campagnes pour Octobre Rose 2024\u201d. Publi\u00e9 le 10 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/2024\/10\/16\/quelle-campagne-choisir-pour-octobre-rose\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Quelle campagne pour Octobre Rose ?\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":3,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"predecessor-version":[{"id":38,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/32\/revisions\/38"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}