{"id":288,"date":"2026-03-10T12:04:10","date_gmt":"2026-03-10T11:04:10","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/?p=288"},"modified":"2026-03-31T16:13:51","modified_gmt":"2026-03-31T14:13:51","slug":"dou-viennent-les-artistes-des-trans-musicales","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/2026\/03\/10\/dou-viennent-les-artistes-des-trans-musicales\/","title":{"rendered":"D&rsquo;o\u00f9 viennent les artistes des Trans Musicales ?"},"content":{"rendered":"\n<p><em>Implant\u00e9 \u00e0 Rennes, les Trans Musicales est un festival de musique ayant accueilli de nombreux artistes \u00e9mergeants. C&rsquo;est 60 000 festivaliers et environ 80 artistes qui viennent chaque ann\u00e9e depuis 1979. \u00c0 cette occasion, la ville devient un laboratoire musical. Le festival propose des concerts vari\u00e9s et audacieux. C\u2019est un rendez-vous incontournable pour les amateurs de d\u00e9couvertes.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2026\/03\/trans-musicales-rennes-malouve-magalir-960x640-1.jpg\" alt=\"\" class=\"wp-image-293\" style=\"width:516px;height:auto\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2026\/03\/trans-musicales-rennes-malouve-magalir-960x640-1.jpg 960w, https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-content\/uploads\/2026\/03\/trans-musicales-rennes-malouve-magalir-960x640-1-300x200.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p><strong>Mais alors d&rsquo;o\u00f9 viennent ces artistes ?<\/strong><\/p>\n\n\n\n<p>La premi\u00e8re carte met en lumi\u00e8re les origines fran\u00e7aises des musiciens programm\u00e9s. Par raison de proximit\u00e9, une grande majorit\u00e9 des artistes proviennent d&rsquo;Europe et plus particuli\u00e8rement de France. Rennes et Paris sont notamment les villes d&rsquo;o\u00f9 proviennent la majorit\u00e9 des artistes.<\/p>\n\n\n\n<p>Cependant, les Trans accueillent aussi beaucoup d&rsquo;artistes internationales. La seconde carte r\u00e9v\u00e8le l\u2019ampleur du r\u00e9seau international de l\u2019\u00e9v\u00e9nement : des artistes venus d\u2019Europe, d\u2019Am\u00e9rique, d\u2019Afrique, d\u2019Asie et d\u2019Oc\u00e9anie ont foul\u00e9 les sc\u00e8nes rennaises depuis la cr\u00e9ation du festival.<\/p>\n\n\n\n<p>Ces donn\u00e9es illustrent le r\u00f4le central des Trans Musicales : faire d\u00e9couvrir des talents venus de partout et nourrir un dialogue musical mondial tout en affirmant un ancrage fort en France.<\/p>\n\n\n\n<p>Carte internationale : <a href=\"https:\/\/datawrapper.dwcdn.net\/7I3QY\/2\">https:\/\/datawrapper.dwcdn.net\/7I3QY\/2<\/a><\/p>\n\n\n\n<p>Carte France : <a href=\"https:\/\/datawrapper.dwcdn.net\/nuzUE\/1\">https:\/\/datawrapper.dwcdn.net\/nuzUE\/1<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Implant\u00e9 \u00e0 Rennes, les Trans Musicales est un festival de musique ayant accueilli de nombreux artistes \u00e9mergeants. C&rsquo;est 60 000 festivaliers et environ 80 artistes qui viennent chaque ann\u00e9e depuis 1979. \u00c0 cette occasion, la ville devient un laboratoire musical. Le festival propose des concerts vari\u00e9s et audacieux. C\u2019est un rendez-vous incontournable pour les amateurs &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/2026\/03\/10\/dou-viennent-les-artistes-des-trans-musicales\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0D&rsquo;o\u00f9 viennent les artistes des Trans Musicales ?\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-288","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/comments?post=288"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/288\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/posts\/288\/revisions\/294"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/media?parent=288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/categories?post=288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/clhenaff\/wp-json\/wp\/v2\/tags?post=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}