{"id":12,"date":"2024-09-10T17:03:00","date_gmt":"2024-09-10T15:03:00","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/?p=12"},"modified":"2024-09-10T17:03:00","modified_gmt":"2024-09-10T15:03:00","slug":"mon-deuxieme-article","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/2024\/09\/10\/mon-deuxieme-article\/","title":{"rendered":"Mon deuxi\u00e8me article :)"},"content":{"rendered":"\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/NPSvCJ9v7vI?si=GfM6UoWI4kSTizwW\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-content\/uploads\/2024\/09\/dadju.jpeg\" alt=\"\" class=\"wp-image-16\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-content\/uploads\/2024\/09\/dadju.jpeg 640w, https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-content\/uploads\/2024\/09\/dadju-300x300.jpeg 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-content\/uploads\/2024\/09\/dadju-150x150.jpeg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/posts\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"predecessor-version":[{"id":17,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/posts\/12\/revisions\/17"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/cbercot\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}