{"id":86,"date":"2024-11-20T20:16:34","date_gmt":"2024-11-20T19:16:34","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/?p=86"},"modified":"2024-11-20T20:16:34","modified_gmt":"2024-11-20T19:16:34","slug":"france-vs-all-blacks","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/2024\/11\/20\/france-vs-all-blacks\/","title":{"rendered":"France VS All Blacks !"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-1024x576.jpg\" alt=\"\" class=\"wp-image-89\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-1024x576.jpg 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-300x169.jpg 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-768x432.jpg 768w, https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-1536x864.jpg 1536w, https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-content\/uploads\/2024\/11\/000-36mp47f-6739186a2d013421511148-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dit photo : ANNE-CHRISTINE POUJOULAT<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Durant la soir\u00e9e du samedi 16 novembre 2024, a eu lieu le match de l&rsquo;ann\u00e9e et le XV de France. La France s&rsquo;est oppos\u00e9e \u00e0 l&rsquo;\u00e9quipe de Nouvelle-Z\u00e9lande : les All Blacks.<\/p>\n\n\n\n<p>La premi\u00e8re p\u00e9riode du match n&rsquo;\u00e9tait pas en faveur de nos bleus, mais ils sont repass\u00e9s devant \u00e0 la 44\u1d49 minute pour finalement sortir victorieux de ce match. La France l&#8217;emporte 30-29 face aux N\u00e9o-z\u00e9landais. 5 essais ont \u00e9t\u00e9 inscrits,&nbsp; par <strong>Paul Boudehent<\/strong>, <strong>Louis Bielle-Biarrey<\/strong>, <strong>Thomas Ramos<\/strong> et <strong>Romain Buros<\/strong>.<\/p>\n\n\n\n<p>Cela fait la 3\u1d49 fois d&rsquo;affil\u00e9e que la France gagne face aux All Blacks !<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/fr.themedialeader.com\/wp-content\/uploads\/files\/media\/images\/2023-03\/nl2879-nl-rugby%20france%20TV.jpg\" alt=\"Rugby : 7,3 millions de t\u00e9l\u00e9spectateurs pour France-All Blacks\" title=\"Rugby : 7,3 millions de t\u00e9l\u00e9spectateurs pour France-All Blacks\"\/><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dit photo : TF1<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Personnellement, le moment fort du match est lorsque<strong> Louis Bielle-Biarrey<\/strong> a travers\u00e9 la moiti\u00e9 du terrain \u00e0 pleine vitesse pour finir en beaut\u00e9 par un essai.<\/p>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/6UEUC4g9UAs?si=zl0PNzjW6Sik7HTI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p>Ce match plein de rebondissements a atteint un record d&rsquo;audience, car 7,3 millions de t\u00e9l\u00e9spectateurs ont suivi sur TF1 la victoire de prestige du XV de France. D&rsquo;apr\u00e8s le m\u00e9dia <strong>The Media Leader<\/strong>, TF1 a atteint 37,4% de part d\u2019audience. Elle a largement distanc\u00e9 la concurrence. Mais sur le r\u00e9seau social X, la cha\u00eene \u00e9voque un pic d\u2019audience \u00e0 8,3 millions de t\u00e9l\u00e9spectateurs et parle \u00ab\u00a0d&rsquo;un record historique\u00a0\u00bb.<\/p>\n\n\n\n<p>Pendant ce type de match, l&#8217;emporter sur une \u00e9quipe l\u00e9gendaire que sont les All Blacks devient un moment historique et de fiert\u00e9 nationale. Les r\u00e9seaux sociaux et les m\u00e9dias accentuent ces sentiments en repartageant les moments forts. De plus, la victoire serr\u00e9e des bleus (30-29) am\u00e8ne un storytelling, qui est une technique de communication marketing qui consiste \u00e0 promouvoir une id\u00e9e \u00e0 travers le r\u00e9cit qu&rsquo;on en fait, et favorise l&rsquo;image des joueurs fran\u00e7ais.<\/p>\n\n\n\n<p>Tout cela montre comment un \u00e9v\u00e8nement sportif d\u00e9passe l&rsquo;\u00e9chelle locale et devient un outil de communication \u00e0 l&rsquo;international ! Des vid\u00e9os des essais fran\u00e7ais faisaient d\u00e9j\u00e0 le tour du monde alors que le match n&rsquo;\u00e9tait m\u00eame pas encore termin\u00e9. <\/p>\n\n\n\n<p>Le r\u00e9sum\u00e9 du match publi\u00e9 sur la cha\u00eene YouTube de TF1 a fait 1 million de vues en 2 jours : <\/p>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/F1w_Lqul0H8?si=ixaiUJcbQY9HkBGx\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p>Sources : <\/p>\n\n\n\n<p><a href=\"https:\/\/fr.themedialeader.com\/rugby-73-millions-de-telespectateurs-pour-france-all-blacks\">https:\/\/fr.themedialeader.com\/rugby-73-millions-de-telespectateurs-pour-france-all-blacks<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.francetvinfo.fr\/sports\/rugby\/xv-de-france\/france-nouvelle-zelande-heroiques-les-bleus-renversent-les-all-blacks-pour-signer-un-exploit_6901529.html\">https:\/\/www.francetvinfo.fr\/sports\/rugby\/xv-de-france\/france-nouvelle-zelande-heroiques-les-bleus-renversent-les-all-blacks-pour-signer-un-exploit_6901529.html<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant la soir\u00e9e du samedi 16 novembre 2024, a eu lieu le match de l&rsquo;ann\u00e9e et le XV de France. La France s&rsquo;est oppos\u00e9e \u00e0 l&rsquo;\u00e9quipe de Nouvelle-Z\u00e9lande : les All Blacks. La premi\u00e8re p\u00e9riode du match n&rsquo;\u00e9tait pas en&#8230; <a class=\"more-link\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/2024\/11\/20\/france-vs-all-blacks\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-sport"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":17,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"predecessor-version":[{"id":104,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/86\/revisions\/104"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}