{"id":322,"date":"2024-12-17T19:36:49","date_gmt":"2024-12-17T18:36:49","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/?p=322"},"modified":"2024-12-17T19:36:49","modified_gmt":"2024-12-17T18:36:49","slug":"wwf-france-et-isoskele-agissent-contre-le-dereglement-climatique","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/2024\/12\/17\/wwf-france-et-isoskele-agissent-contre-le-dereglement-climatique\/","title":{"rendered":"WWF France et Isosk\u00e8le agissent contre le d\u00e9r\u00e8glement climatique !"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/jai-un-pote-dans-la.com\/wp-content\/uploads\/2022\/11\/jupdlc-wwf-isoskele-campagne-collecte-dons.jpg\" alt=\"campagne-collecte-dons-isoskele-non-profit-wwf\" class=\"wp-image-85464\" style=\"width:871px;height:auto\"\/><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dit photo : WWF<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Au vu de la situation critique dans laquelle la faune &amp; la flore de la Terre se trouvent, les deux groupes <strong>Isosk\u00e8le<\/strong> et <strong>WWF France<\/strong> s&rsquo;associent pour pr\u00e9server l&rsquo;environnement.<\/p>\n\n\n\n<p>L&rsquo;agence <strong>Isosk\u00e8le<\/strong>, cr\u00e9\u00e9e par <strong>La Poste<\/strong>, regroupe cinq filiales\u00a0: <strong>Mediapost Publicit\u00e9<\/strong> (la r\u00e9gie du Home Media), <strong>Mediaprism l\u2019Agence<\/strong> (sp\u00e9cialiste data et marketing relationnel), <strong>Vertical-Mail<\/strong> (experte des strat\u00e9gies d\u2019acquisition B2B), <strong>Cabestan<\/strong> (sp\u00e9cialiste des services aff\u00e9rant aux logiciels CRM) et <strong>SDS<\/strong> (Smart Datamark Services, qui optimise les bases de donn\u00e9es). Elle se sp\u00e9cialise en data marketing et communication. Le Fonds Mondial pour la Nature (<strong>WWF<\/strong>) est l&rsquo;une des toutes premi\u00e8res organisations ind\u00e9pendantes de protection de l&rsquo;environnement dans le monde.\u00a0Depuis 1973, le <strong>WWF\u00a0France<\/strong> \u0153uvre pour une plan\u00e8te vivante depuis Paris, Marseille, les Alpes, la Guyane et la Nouvelle-Cal\u00e9donie.<\/p>\n\n\n\n<p>Ainsi, ces deux groupes agissent pour lutter contre le d\u00e9r\u00e8glement climatique. L&rsquo;objectif de cette campagne est de d\u00e9noncer les solutions absurdes face \u00e0 ce d\u00e9r\u00e8glement climatique. Que ce soit l\u2019installation de climatiseurs pour refroidir la banquise, le fait de repeindre les coraux pour leur rendre vie, balancer dans les nuages des fus\u00e9es charg\u00e9es d\u2019iodures d\u2019argent afin qu\u2019il pleuve avant d\u2019arriver au-dessus de la ville ou encore balancer des produits chimiques sur les p\u00f4les pour les refroidir.<br>La campagne veut mettre en lumi\u00e8re l\u2019urgence d\u2019agir et valoriser les actions concr\u00e8tes et efficaces du <strong>WWF France<\/strong> \u00e0 travers des images r\u00e9alis\u00e9es \u00e0 l&rsquo;aide de l&rsquo;IA :<br><\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/www.legorafi.fr\/wp-content\/uploads\/2024\/11\/Publication-OURS-good-size.jpg\" alt=\"\" style=\"width:538px;height:auto\"\/><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dit photo : Gorafi<\/strong><\/figcaption><\/figure>\n\n\n\n<p>De plus, cette campagne se d\u00e9ploie sur le digital, avec des relais sur les r\u00e9seaux sociaux, le Search et des e-mailings, notamment en s\u2019associant avec<strong> Gorafi<\/strong>.<\/p>\n\n\n\n<p>Depuis bien trop longtemps, la plan\u00e8te subit un d\u00e9r\u00e8glement suite aux activit\u00e9s humaines. La campagne s\u2019appuie sur le constat\u00a0que les populations d\u2019esp\u00e8ces sauvages ont diminu\u00e9 de <strong>69 %<\/strong> depuis <strong>1970<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/jai-un-pote-dans-la.com\/wp-content\/uploads\/2022\/11\/jupdlc-wwf-isoskele-campagne-collecte-dons2.jpg\" alt=\"campagne-collecte-dons-isoskele-non-profit-wwf\" class=\"wp-image-85465\" style=\"width:1015px;height:auto\"\/><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dit photo  : WWF<\/strong><\/figcaption><\/figure>\n\n\n\n<p>\u00c0 travers toute cette sensibilisation, le but est de r\u00e9colter des dons pour le<strong> WWF<\/strong>, afin d&rsquo;obtenir des financements pour la protection des esp\u00e8ces et des v\u00e9g\u00e9taux. Pour prot\u00e9ger la plan\u00e8te, il est n\u00e9cessaire d\u2019\u00eatre pr\u00e9sent dans les oc\u00e9ans, dans les for\u00eats ou dans la vie sauvage. Le <strong>WWF <\/strong>cr\u00e9e gr\u00e2ce aux dons des zones marines prot\u00e9g\u00e9es, lutte activement contre le braconnage, sanctuarise des for\u00eats qui ont une valeur inestimable\u2026 \u00c0 seulement 19 jours de la fin de la campagne de sensibilisation, l&rsquo;association a r\u00e9colt\u00e9 <strong>119 358 euros<\/strong>. Enfin, gr\u00e2ce au relayage sur les diff\u00e9rents r\u00e9seaux (TikTok, YouTube, Instagram\u2026), une bonne partie des jeunes vont \u00eatre touch\u00e9s, sachant que ce sont eux les g\u00e9n\u00e9rations futures qui devront vivre dans ce monde encore plus affect\u00e9 par l&rsquo;Homme. Mais il n&rsquo;est pas encore trop tard pour agir !!!<\/p>\n\n\n\n<p><strong>Campagne WWF &#8211; Les records \u00e0 ne pas battre :<\/strong><\/p>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/zvsTUCMPxwU?si=6z1_OVBXlHA-RNPM\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p>Sources : <\/p>\n\n\n\n<p><a href=\"https:\/\/jai-un-pote-dans-la.com\/isoskele-nouvelle-operation-collecte-wwf-france\">https:\/\/jai-un-pote-dans-la.com\/isoskele-nouvelle-operation-collecte-wwf-france<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.wwf.fr\/les-vraies-solutions\">https:\/\/www.wwf.fr\/les-vraies-solutions<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fr.themedialeader.com\/wwf-france-et-isoskele-agissent-contre-le-dereglement-climatique\">https:\/\/fr.themedialeader.com\/wwf-france-et-isoskele-agissent-contre-le-dereglement-climatique<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.legorafi.fr\/2024\/11\/25\/pour-freiner-la-fonte-des-glaces-le-gouvernement-fait-installer-3000-climatiseurs-sur-la-banquise\/?utm_campaign=linkinbio&amp;utm_medium=referral&amp;utm_source=later-linkinbio\">https:\/\/www.legorafi.fr\/2024\/11\/25\/pour-freiner-la-fonte-des-glaces-le-gouvernement-fait-installer-3000-climatiseurs-sur-la-banquise\/?utm_campaign=linkinbio&amp;utm_medium=referral&amp;utm_source=later-linkinbio<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au vu de la situation critique dans laquelle la faune &amp; la flore de la Terre se trouvent, les deux groupes Isosk\u00e8le et WWF France s&rsquo;associent pour pr\u00e9server l&rsquo;environnement. L&rsquo;agence Isosk\u00e8le, cr\u00e9\u00e9e par La Poste, regroupe cinq filiales\u00a0: Mediapost Publicit\u00e9&#8230; <a class=\"more-link\" href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/2024\/12\/17\/wwf-france-et-isoskele-agissent-contre-le-dereglement-climatique\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-322","post","type-post","status-publish","format-standard","hentry","category-environnement"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":15,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/322\/revisions"}],"predecessor-version":[{"id":338,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts\/322\/revisions\/338"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/media?parent=322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/categories?post=322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/tags?post=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}