{"id":10,"count":2,"description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/category\/environnement\/","name":"Environnement","slug":"environnement","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/bcherel\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}