{"id":4,"name":"llancelotkei","url":"","description":"","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/author\/llancelotkei\/","slug":"llancelotkei","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/03ecb7e49f98eb6a0df633363a3f19a4ddbdeb1f64024369e501223f55e084b6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/03ecb7e49f98eb6a0df633363a3f19a4ddbdeb1f64024369e501223f55e084b6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/03ecb7e49f98eb6a0df633363a3f19a4ddbdeb1f64024369e501223f55e084b6?s=96&d=mm&r=g"},"meta":[],"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/users\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/users"}]}}