{"id":5573,"date":"2026-03-31T10:56:55","date_gmt":"2026-03-31T08:56:55","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/kdecaudin\/?p=439"},"modified":"2026-04-08T14:33:49","modified_gmt":"2026-04-08T12:33:49","slug":"orelsan-une-figure-majeure-du-rap-francais","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/2026\/03\/31\/orelsan-une-figure-majeure-du-rap-francais\/","title":{"rendered":"Orelsan : une figure majeure du rap fran\u00e7ais"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/orelsan7th.com\/?utm_source=chatgpt.com\">Orelsan <\/a><\/strong> est l\u2019univers central d\u00e9di\u00e9 \u00e0 l\u2019actualit\u00e9, aux clips, aux paroles et \u00e0 la discographie du rappeur fran\u00e7ais Aur\u00e9lien Cotentin, alias Orelsan. N\u00e9 le 1\u1d49\u02b3\u202fao\u00fbt\u202f1982 \u00e0 Alen\u00e7on, il est devenu l\u2019une des voix les plus influentes du hip\u2011hop en France gr\u00e2ce \u00e0 son \u00e9criture unique, m\u00ealant humour, introspection et observations sociales modernes.<\/p>\n\n\n\n<p>Orelsan s\u2019est d\u2019abord fait conna\u00eetre sur internet avant de sortir son premier album solo <em>Perdu d\u2019avance<\/em> en 2009, qui l\u2019a propuls\u00e9 sur la sc\u00e8ne nationale. Depuis, il a encha\u00een\u00e9 plusieurs projets \u00e0 succ\u00e8s, explorant diff\u00e9rents styles tout en restant fid\u00e8le \u00e0 son identit\u00e9 artistique.<\/p>\n\n\n\n<p>Pour \u00e9couter sa musique en streaming, tu peux visiter sa page <strong><a href=\"https:\/\/open.spotify.com\/intl-fr\/artist\/4FpJcNgOvIpSBeJgRg3OfN?utm_source=chatgpt.com\">Spotify<\/a><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-content\/uploads\/2026\/03\/ORELSAN_TM_PHOTO_FICHE_ARTISTE-1024x575.jpg\" alt=\"\" class=\"wp-image-440\"\/><\/figure>\n\n\n\n<p>Et pour d\u00e9couvrir ses clips et vid\u00e9os officielles, <strong><a href=\"https:\/\/www.youtube.com\/channel\/UCEnFzIYw3BrndPCddyQ6c5A?utm_source=chatgpt.com\">sa cha\u00eene YouTube officielle<\/a><\/strong> contient des millions de vues et des dizaines de vid\u00e9os (dont <em>Encore une fois<\/em>, <em>Soleil levant<\/em> ou <em>Civilisation<\/em>).<\/p>\n\n\n\n<p>Orelsan est aussi actif sur les r\u00e9seaux sociaux, par exemple sur <strong><a href=\"https:\/\/www.instagram.com\/orelsan\/?utm_source=chatgpt.com\">Instagram<\/a><\/strong> o\u00f9 il partage r\u00e9guli\u00e8rement des actualit\u00e9s, teasers et coulisses de ses projets.<\/p>\n\n\n\n<p>Parmi ses albums marquants figurent <em>La f\u00eate est finie<\/em>, <em>Civilisation<\/em> ou encore <em>La fuite en avant<\/em> (sorti en novembre\u202f2025), qui montrent l\u2019\u00e9volution de sa carri\u00e8re et sa capacit\u00e9 \u00e0 rester pertinent et innovant dans un paysage musical toujours plus comp\u00e9titif.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orelsan est l\u2019univers central d\u00e9di\u00e9 \u00e0 l\u2019actualit\u00e9, aux clips, aux paroles et \u00e0 la discographie du rappeur fran\u00e7ais Aur\u00e9lien Cotentin, alias Orelsan. N\u00e9 le 1\u1d49\u02b3\u202fao\u00fbt\u202f1982 \u00e0 Alen\u00e7on, il est devenu l\u2019une des voix les plus influentes du hip\u2011hop en France gr\u00e2ce \u00e0 son \u00e9criture unique, m\u00ealant humour, introspection et observations sociales modernes. Orelsan s\u2019est d\u2019abord &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/2026\/03\/31\/orelsan-une-figure-majeure-du-rap-francais\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Orelsan : une figure majeure du rap fran\u00e7ais\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,18],"tags":[],"class_list":["post-5573","post","type-post","status-publish","format-standard","hentry","category-musique","category-rap"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/comments?post=5573"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5573\/revisions"}],"predecessor-version":[{"id":5649,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5573\/revisions\/5649"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/media?parent=5573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/categories?post=5573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/tags?post=5573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}