{"id":5567,"date":"2026-04-01T14:04:19","date_gmt":"2026-04-01T12:04:19","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/juliriviere\/?p=207"},"modified":"2026-04-08T14:52:09","modified_gmt":"2026-04-08T12:52:09","slug":"riles-lartiste-independant-qui-redefinit-les-regles-du-jeu","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/2026\/04\/01\/riles-lartiste-independant-qui-redefinit-les-regles-du-jeu\/","title":{"rendered":"Ril\u00e8s, l\u2019artiste ind\u00e9pendant qui red\u00e9finit les r\u00e8gles du jeu"},"content":{"rendered":"\n<p class=\"has-text-align-left\"><em>\u00c0 la crois\u00e9e du rap, de la pop et de l\u2019exp\u00e9rimentation sonore,\u00a0Ril\u00e8s\u00a0s\u2019impose comme l\u2019une des figures les plus singuli\u00e8res de la sc\u00e8ne musicale fran\u00e7aise. Enti\u00e8rement autonome, de la production \u00e0 la r\u00e9alisation visuelle, il incarne une nouvelle g\u00e9n\u00e9ration d\u2019artistes capables de b\u00e2tir un univers global sans passer par les circuits traditionnels.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-content\/uploads\/2026\/04\/riles-article--1024x768.webp\" alt=\"\" class=\"wp-image-208\" style=\"width:575px;height:auto\"\/><\/figure>\n\n\n\n<p><strong>Un parcours hors des sentiers battus<\/strong><\/p>\n\n\n\n<p>Originaire de Rouen, Ril\u00e8s se distingue tr\u00e8s t\u00f4t par son approche DIY (Do It Yourself). Il \u00e9crit, compose, enregistre et mixe lui-m\u00eame ses morceaux depuis sa chambre, construisant patiemment une identit\u00e9 artistique forte.<\/p>\n\n\n\n<p>Son projet\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=AitbrbLsVRI&amp;list=PLZ7PzGqEIMhipqpCrOr9zCUyjWKR2jmEP\"><strong>\u201cRil\u00e8sundayz\u201d<\/strong>,<\/a> consistant \u00e0 publier une chanson par semaine pendant un an, marque un tournant d\u00e9cisif. Cette performance impressionnante lui permet de f\u00e9d\u00e9rer une communaut\u00e9 fid\u00e8le et de d\u00e9montrer une cr\u00e9ativit\u00e9 sans rel\u00e2che.<\/p>\n\n\n\n<p><strong>Un univers musical hybride<\/strong><\/p>\n\n\n\n<p>La musique de Ril\u00e8s ne se limite pas \u00e0 un genre. Influenc\u00e9 autant par le rap am\u00e9ricain que par la pop ou l\u2019\u00e9lectro, il navigue entre les styles avec aisance.<\/p>\n\n\n\n<p>Son album\u00a0<a href=\"https:\/\/open.spotify.com\/intl-fr\/album\/78c0MqaiVSdxo38fjv0vcp\">Welcome to the Jungle<\/a>\u00a0illustre parfaitement cette diversit\u00e9. On y trouve des morceaux or du communs, des titres \u00e9nergiques et des exp\u00e9rimentations sonores audacieuses.<\/p>\n\n\n\n<p><strong>Une ma\u00eetrise totale de son image<\/strong><\/p>\n\n\n\n<p>Au-del\u00e0 de la musique, Ril\u00e8s contr\u00f4le \u00e9galement toute sa direction artistique. Clips, visuels, communication, tous les d\u00e9tails ont \u00e9t\u00e9 pens\u00e9s pour renforcer son univers.<\/p>\n\n\n\n<p>Son clip\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=hHOfd7tWZtA&amp;list=RDhHOfd7tWZtA&amp;start_radio=1\">\u201cBrothers\u201d<\/a>\u00a0en est un exemple frappant, m\u00ealant esth\u00e9tique et narration.<\/p>\n\n\n\n<p><strong>Une trajectoire en constante \u00e9volution<\/strong><\/p>\n\n\n\n<p>Toujours en qu\u00eate de nouveaut\u00e9, Ril\u00e8s continue d\u2019explorer de nouvelles directions artistiques. Son ambition d\u00e9passe les fronti\u00e8res fran\u00e7aises, avec une reconnaissance allant jusqu&rsquo;\u00e0 l\u2019international.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 la crois\u00e9e du rap, de la pop et de l\u2019exp\u00e9rimentation sonore,\u00a0Ril\u00e8s\u00a0s\u2019impose comme l\u2019une des figures les plus singuli\u00e8res de la sc\u00e8ne musicale fran\u00e7aise. Enti\u00e8rement autonome, de la production \u00e0 la r\u00e9alisation visuelle, il incarne une nouvelle g\u00e9n\u00e9ration d\u2019artistes capables de b\u00e2tir un univers global sans passer par les circuits traditionnels. Un parcours hors des &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/2026\/04\/01\/riles-lartiste-independant-qui-redefinit-les-regles-du-jeu\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Ril\u00e8s, l\u2019artiste ind\u00e9pendant qui red\u00e9finit les r\u00e8gles du jeu\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,26,18,22],"tags":[],"class_list":["post-5567","post","type-post","status-publish","format-standard","hentry","category-pop","category-pop-urbaine","category-rap","category-rap-francais"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/comments?post=5567"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5567\/revisions"}],"predecessor-version":[{"id":5661,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/posts\/5567\/revisions\/5661"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/media?parent=5567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/categories?post=5567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/anmoalic\/wp-json\/wp\/v2\/tags?post=5567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}