{"id":179,"date":"2024-12-03T14:44:33","date_gmt":"2024-12-03T13:44:33","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/?p=179"},"modified":"2024-12-03T17:56:43","modified_gmt":"2024-12-03T16:56:43","slug":"avec-enigma-louis-vuitton-plonge-dans-le-monde-du-numerique-avec-son-premier-jeu-immersif-sur-discord","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/2024\/12\/03\/avec-enigma-louis-vuitton-plonge-dans-le-monde-du-numerique-avec-son-premier-jeu-immersif-sur-discord\/","title":{"rendered":"Avec Enigma, Louis Vuitton plonge dans le monde du num\u00e9rique avec son premier jeu immersif sur Discord !"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/jupdlc-louis-vuitton-enigma-2-1024x536.webp\" alt=\"\" class=\"wp-image-180\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/jupdlc-louis-vuitton-enigma-2-1024x536.webp 1024w, https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/jupdlc-louis-vuitton-enigma-2-300x157.webp 300w, https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/jupdlc-louis-vuitton-enigma-2.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Cr\u00e9dits photo: <a href=\"https:\/\/jai-un-pote-dans-la.com\/louis-vuitton-lance-son-premier-jeu-immersif-sur-discord\/\">https:\/\/jai-un-pote-dans-la.com\/louis-vuitton-lance-son-premier-jeu-immersif-sur-discord\/<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<p>Un article de <a href=\"https:\/\/jai-un-pote-dans-la.com\/louis-vuitton-lance-son-premier-jeu-immersif-sur-discord\/\" data-type=\"link\" data-id=\"https:\/\/jai-un-pote-dans-la.com\/louis-vuitton-lance-son-premier-jeu-immersif-sur-discord\/\">J&rsquo;ai un pote dans la com<\/a> r\u00e9v\u00e8le que pour f\u00eater son premier anniversaire de sa plateforme Discord, Louis Vuitton lance Enigma, un jeu interactif qui se joue en collectif. Du 26 au 30 novembre, les 8000 membres de la communaut\u00e9 sont invit\u00e9s \u00e0 r\u00e9soudre une \u00e9nigme pour retrouver Vivienne, la mascotte embl\u00e9matique de la marque perdue. Les joueurs r\u00e9partis en \u00e9quipe doivent d\u00e9crypter les indices pour d\u00e9couvrir la solution au myst\u00e8re. Ce jeu a pour but de r\u00e9compenser a communaut\u00e9 deLouis Vuitton sur Discord, de consolider les liens entre la communaut\u00e9 et de s&rsquo;aligner avec la strat\u00e9gie num\u00e9rique de Louis Vuitton, lanc\u00e9 sur Discord depuis 2023.<\/p>\n\n\n\n<p>J&rsquo;ai choisi cet article, car j&rsquo;ai trouv\u00e9 int\u00e9ressante la mani\u00e8re dont Louis Vuitton, marque connue pour son h\u00e9ritage et son prestige, utilise les nouveaux outils num\u00e9riques comme Discord pour communiquer. En effet, beaucoup de marques de luxe ne vendent pas encore en ligne. Je trouve \u00e7a donc int\u00e9ressant de constater que ces marques tente d&rsquo;utiliser le tournant num\u00e9rique dans leurs strat\u00e9gie de communication.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Plusieurs th\u00e8mes se d\u00e9gagent de l&rsquo;article:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 38%\"><div class=\"wp-block-media-text__content\">\n<p><strong>En quoi les plateformes comme Discord offrent des opportunit\u00e9s pour les marques ?<\/strong> <a href=\"https:\/\/www.grenier.qc.ca\/actualites\/30787\/discord-quel-interet-pour-les-marques#:~:text=Avec%20le%20marketing%20plus%20traditionnel,probablement%20jouer%20en%20sa%20faveur.\" data-type=\"link\" data-id=\"https:\/\/www.grenier.qc.ca\/actualites\/30787\/discord-quel-interet-pour-les-marques#:~:text=Avec%20le%20marketing%20plus%20traditionnel,probablement%20jouer%20en%20sa%20faveur.\">L&rsquo;article du Grenier<\/a> r\u00e9v\u00e8le que les plateformes telles que Discord donnent aux marques de nouvelles fa\u00e7ons de communiquer et de davantage s&rsquo;engager avec leur communaut\u00e9. En effet, en regroupant des discussions, des audios ou des vid\u00e9os en un seul endroit accessible sur invitation, Discord contribue \u00e0 rapprocher les marques et leurs consommateurs. La plateforme peut recueillir des avis, des retours\u2026 \u00e0 travers ces discussions avec leur communaut\u00e9, ce qui renforce \u00e9videmment leur engagement. De plus, cela permet aux marques de r\u00e9agir rapidement aux pr\u00e9occupations des consommateurs ou aux tendances du march\u00e9.&nbsp;<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.grenier.qc.ca\"><img decoding=\"async\" width=\"310\" height=\"163\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/grenier-image.png\" alt=\"\" class=\"wp-image-181 size-full\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/grenier-image.png 310w, https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/grenier-image-300x158.png 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 37%\"><div class=\"wp-block-media-text__content\">\n<p><strong>Comment une marque peut-elle adapter ses strat\u00e9gies de communication aux plateformes num\u00e9riques tout en restant fid\u00e8le \u00e0 son identit\u00e9 ?<\/strong> Un article de <a href=\"https:\/\/blog.neocamino.com\/strategie-communication-digitale\/\" data-type=\"link\" data-id=\"https:\/\/blog.neocamino.com\/strategie-communication-digitale\/\">N\u00e9oCamino Le Blog<\/a> insiste sur l&rsquo;importance pour une marque d&rsquo;adapter sa strat\u00e9gie num\u00e9rique en fonction de son identit\u00e9. Il est primordial de garder une image coh\u00e9rente en ligne et hors ligne pour maintenir une cr\u00e9dibilit\u00e9 aupr\u00e8s des consommateurs. Par exemple, la marque Cama\u00efeu est le parfait exemple d&rsquo;une marque qui n&rsquo;a pas su r\u00e9ussir sa transition num\u00e9rique. En effet, la marque manquait de coh\u00e9rence, son site internet n&rsquo;\u00e9tait pas int\u00e9gr\u00e9 avec les stocks des magasins physiques, ce qui frustrait les clients. Elle n&rsquo;a pas su rivaliser avec des concurrents tels que Zara et H&amp;M, ce qui a pr\u00e9cipit\u00e9 sa liquidation en 2022. Alors, il est primordial de rester coh\u00e9rent avec les valeurs de sa marque pour ne pas perdre les consommateurs et leur faciliter l&rsquo;accompagnement vers une transition num\u00e9rique.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/services.wizishop.com\/fr\/service\/neocamino\"><img decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/neocamino.png\" alt=\"\" class=\"wp-image-182 size-full\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 39%\"><div class=\"wp-block-media-text__content\">\n<p><strong>Le digital est-il un essentiel pour les communicants aujourd&rsquo;hui ?<\/strong> <a href=\"https:\/\/blog.whaller.com\/2024\/07\/01\/revolution-numerique-whaller-communication-collaborative\/\" data-type=\"link\" data-id=\"https:\/\/blog.whaller.com\/2024\/07\/01\/revolution-numerique-whaller-communication-collaborative\/\">L&rsquo;article de Whaller Blog<\/a> r\u00e9v\u00e8le que le num\u00e9rique est devenu un \u00e9l\u00e9ment incontournable pour les communicants. Effectivement, les r\u00e9seaux sociaux, les plateformes collaboratives facilitent une communication rapide, ce qui est primordial dans cet environnement o\u00f9 les consommateurs sont de plus en plus quotidiennement connect\u00e9s. Le SEO (optimisation pour les moteurs de recherche)&nbsp;, le SEM (search engine marketing) ou les directs sont primordials pour maintenir une visibilit\u00e9 en ligne efficace. La communication num\u00e9rique est donc un essentiel pour s&rsquo;adapter aux nouvelles attentes du march\u00e9 o\u00f9 le num\u00e9rique influence directement la fa\u00e7on dont les consommateurs prennent leurs d\u00e9cisions.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/blog.whaller.com\"><img loading=\"lazy\" decoding=\"async\" width=\"317\" height=\"159\" src=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/whaller-blog.jpeg\" alt=\"\" class=\"wp-image-183 size-full\" srcset=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/whaller-blog.jpeg 317w, https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-content\/uploads\/2024\/12\/whaller-blog-300x150.jpeg 300w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>En conclusion, la strat\u00e9gie de communication adopt\u00e9e par Louis Vuitton avec le lancement d\u2019Enigma nous emm\u00e8ne \u00e0 r\u00e9fl\u00e9chir \u00e0 l\u2019\u00e9volution des pratiques concernant l\u2019utilisation des plateformes num\u00e9riques. Cela montre \u00e0 quel point le digital est devenu important dans les strat\u00e9gies de communication des marques, non seulement pour toucher de nouveaux publics mais aussi pour r\u00e9pondre aux attentes des consommateurs qui demande a \u00eatre d&rsquo;avantage en interaction avec les marques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un article de J&rsquo;ai un pote dans la com r\u00e9v\u00e8le que pour f\u00eater son premier anniversaire de sa plateforme Discord, Louis Vuitton lance Enigma, un jeu interactif qui se joue en collectif. Du 26 au 30 novembre, les 8000 membres de la communaut\u00e9 sont invit\u00e9s \u00e0 r\u00e9soudre une \u00e9nigme pour retrouver Vivienne, la mascotte embl\u00e9matique &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/2024\/12\/03\/avec-enigma-louis-vuitton-plonge-dans-le-monde-du-numerique-avec-son-premier-jeu-immersif-sur-discord\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Avec Enigma, Louis Vuitton plonge dans le monde du num\u00e9rique avec son premier jeu immersif sur Discord !\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-179","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":3,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"predecessor-version":[{"id":186,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/posts\/179\/revisions\/186"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/angallais\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}