{"id":87,"date":"2024-11-20T17:47:53","date_gmt":"2024-11-20T16:47:53","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/?p=87"},"modified":"2024-11-20T17:47:53","modified_gmt":"2024-11-20T16:47:53","slug":"article-de-veille-4","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/2024\/11\/20\/article-de-veille-4\/","title":{"rendered":"Article de veille 4"},"content":{"rendered":"\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/guObMVercYE?si=Jb5CyreQFe3edqzY\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Choix de l&rsquo;article <\/h2>\n\n\n\n<p>Comme les f\u00eates de No\u00ebl approchent \u00e0 grands pas, j\u2019ai d\u00e9cid\u00e9 de me tourner dans cet article de veille vers les publicit\u00e9s de No\u00ebl des grandes marques. En effet, j\u2019ai choisi un article du site \u00a0\u00bb <a href=\"http:\/\/1)\thttps:\/\/jai-un-pote-dans-la.com\/sephora-reinvente-les-traditions-de-noel-dans-son-nouveau-spot\/\">J&rsquo;ai un pote dans la com <\/a>\u00a0\u00bb qui d\u00e9crypte et parle de la nouvelle campagne de No\u00ebl de la marque de beaut\u00e9 S\u00e9phora, en collaboration avec BETC Etoile Rouge et BETC Fullsix. Cet article nous montre que la marque essaye de se d\u00e9marquer en r\u00e9inventant les traditions festives. Dans son film publicitaire, S\u00e9phora illustre la cr\u00e9ation collective d\u2019un sapin unique dans un parc, c\u00e9l\u00e9brant l\u2019esprit de partage. La marque a choisi de revisiter le sapin traditionnel avec des boules roses, argent\u00e9es\u2026 ce qui le fait devenir un symbole central de la campagne, visible sur tous les autres supports comme les magasins, l&rsquo;affichage, la t\u00e9l\u00e9vision, les r\u00e9seaux sociaux et autres m\u00e9dias. J\u2019ai alors choisi cet article car tous les ans je trouve int\u00e9ressant de regarder les campagnes qui sont faites par les grandes marques au moment de No\u00ebl. Effectivement, je trouve que c\u2019est le moment de l\u2019ann\u00e9e o\u00f9 les marques sont les plus cr\u00e9atives dans leurs campagnes de communication. S\u00e9phora rentre alors parfaitement dans cette id\u00e9e d\u2019utiliser les f\u00eates de No\u00ebl pour se d\u00e9marquer \u00e0 travers une campagne de communication.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Elargissement du sujet <\/h2>\n\n\n\n<p>Cette campagne de publicit\u00e9 de S\u00e9phora permet de nous tourner vers la dynamique qui \u00e9merge autour des campagnes de communication de nombreuses grandes marques. En effet, \u00e0 partir de novembre, de nombreuses marques utilisent les f\u00eates de fin d\u2019ann\u00e9e comme th\u00e8me pour leur nouvelle campagne en cherchant \u00e0 \u00eatre le plus ing\u00e9nieux et cr\u00e9atif possible. Cet article t\u00e9moigne ainsi de l&rsquo;\u00e9volution des campagnes de No\u00ebl. En effet, elles ne se limitent plus \u00e0 c\u00e9l\u00e9brer la tradition classique, mais cherchent \u00e0 surprendre, \u00e9mouvoir et inclure, tout en s&rsquo;alignant sur des valeurs modernes et universelles. C\u2019est pourquoi nous pouvons nous tourner vers un article de \u00ab<a href=\"https:\/\/lareclame.fr\/meilleures-pubs-noel-2023-290276\">\u00a0La R\u00e9clame\u00a0<\/a>\u00bb qui dresse un panorama des meilleures publicit\u00e9s de No\u00ebl 2023. Il parle, par exemple, de la <a href=\"https:\/\/youtu.be\/Fvsfh_Tbm6k\">publicit\u00e9 de Telstra<\/a> proposant une histoire touchante d&rsquo;une petite fille aidant un renne \u00e9gar\u00e9 en Australie, ou encore l\u2019incontestable campagne de Coca-Cola qui valorise la g\u00e9n\u00e9rosit\u00e9 avec \u00ab\u00a0<a href=\"https:\/\/youtu.be\/znIyaGS5BNc\">Le Monde a Besoin de Plus de P\u00e8res No\u00ebl<\/a>\u00ab\u00a0. On peut ainsi observer que cet article met en lumi\u00e8re le fait que les marques utilisent cette p\u00e9riode pour marquer les esprits de leurs publics.<\/p>\n\n\n\n<p>Pour continuer, la campagne de communication de No\u00ebl de S\u00e9phora permet d\u2019illustrer le fait que les marques recherchent l\u2019innovation dans leur campagne de No\u00ebl. Nous pouvons alors nous tourner vers un article de \u00ab\u00a0<a href=\"https:\/\/jai-un-pote-dans-la.com\/coca-cola-noel-2024\/\">j\u2019ai un pote dans la com\u00a0<\/a>\u00bb qui s\u2019int\u00e9resse \u00e0 la campagne de communication de Coca-Cola. La marque associe les traditions de No\u00ebl avec l\u2019innovation gr\u00e2ce \u00e0 l&rsquo;IA. Cette campagne illustre ainsi le fait que les marques sont toujours \u00e0 la recherche d\u2019innovation pour captiver les consommateurs, ce qui entraine une \u00e9volution de ces campagnes de No\u00ebl. Ici, Coca-Cola met en place des exp\u00e9riences interactives, mais tout en conservant l\u2019id\u00e9e universelle de bont\u00e9 et de g\u00e9n\u00e9rosit\u00e9 de No\u00ebl. Coca-Cola a \u00e9galement remis en place un film publicitaire comme l\u2019ann\u00e9e derni\u00e8re. Cela nous permet alors d\u2019observer que de plus en plus de marques produisent \u00e9galement des publicit\u00e9s long format lors des p\u00e9riodes de No\u00ebl, comme celle d\u2019Intermarch\u00e9 que nous connaissons tous, ou encore celle de <a href=\"https:\/\/www.danstapub.com\/ikea-pub-noel-teckel-2024\/\">Ikea<\/a> (ici en Pologne). \u00a0<\/p>\n\n\n\n<p>Terminons cet article avec quelques publicit\u00e9s de Noel : <\/p>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/55ghIHTaRzM?si=qv81DiWlh0JWjOgt\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/ecV3E779MfU?si=TnBWwohqKo9BF_Zq\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/3iPshsgPC9w?si=OAD3YTBczaZDQZS-\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Choix de l&rsquo;article Comme les f\u00eates de No\u00ebl approchent \u00e0 grands pas, j\u2019ai d\u00e9cid\u00e9 de me tourner dans cet article de veille vers les publicit\u00e9s [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-87","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":2,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/posts\/87\/revisions\/89"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/aliclepage\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}