{"id":33,"date":"2024-11-18T16:42:58","date_gmt":"2024-11-18T15:42:58","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/?p=33"},"modified":"2024-11-18T16:42:58","modified_gmt":"2024-11-18T15:42:58","slug":"rester-pertinent-face-a-ces-cibles-le-defi-des-marques-aujourdhui","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/2024\/11\/18\/rester-pertinent-face-a-ces-cibles-le-defi-des-marques-aujourdhui\/","title":{"rendered":"Rester pertinent face \u00e0 ces cibles : le d\u00e9fi des marques aujourd\u2019hui"},"content":{"rendered":"\n<p>Le 14 novembre 2024, <em>La R\u00e9clame<\/em> a publi\u00e9 un article intitul\u00e9 \u201c<a href=\"https:\/\/lareclame.fr\/gangsteres-thesource-parole-annonceur-yop-yoplait-jeunes-306280\" data-type=\"link\" data-id=\"https:\/\/lareclame.fr\/gangsteres-thesource-parole-annonceur-yop-yoplait-jeunes-306280\">Comment Yop continue \u00e0 parler \u2018jeunes\u2019 \u00e0 50 ans <\/a>?\u201d. Cet article analyse la strat\u00e9gie de communication de YOP, marque embl\u00e9matique de yaourts \u00e0 boire, qui s\u2019efforce depuis cinq d\u00e9cennies de rester connect\u00e9e \u00e0 un public adolescent en perp\u00e9tuelle \u00e9volution. En misant notamment sur TikTok et en collaborant avec un groupe d\u2019adolescents pour valider ses contenus, YOP adapte son discours pour rester pertinent aupr\u00e8s de cette cible exigeante.\u00a0L\u2019aspect qui m\u2019a particuli\u00e8rement marqu\u00e9 est le concept du \u201ccrew\u201d. Il s\u2019agit d\u2019un groupe WhatsApp compos\u00e9 de jeunes consommateurs de YOP, o\u00f9 la marque partage ses cr\u00e9ations de communication pour recueillir leurs avis. Cette d\u00e9marche participative influence directement la strat\u00e9gie de YOP et illustre une approche cr\u00e9ative pour mieux comprendre et r\u00e9pondre aux attentes de son publique cible.\u00a0<\/p>\n\n\n\n<p>Cet article m\u2019a pouss\u00e9 \u00e0 r\u00e9fl\u00e9chir sur deux points : d\u2019abord, comment les marques s\u2019adaptent-elles aux \u00e9volutions constantes de leurs cibles\u202f? Ensuite, quelles techniques de communication innovantes permettent de rester en phase avec ces attentes\u202f?&nbsp;<\/p>\n\n\n\n<p>L&rsquo;article souligne \u00e9galement l&rsquo;importance de plateformes comme TikTok, que YOP privil\u00e9gie pour sa capacit\u00e9 \u00e0 transmettre des contenus per\u00e7us comme authentiques, moins travaill\u00e9s, et refl\u00e9tant la \u00ab vraie vie \u00bb.\u00a0<\/p>\n\n\n\n<p>En parall\u00e8le, une <a href=\"https:\/\/www.fevad.com\/la-gen-z-stimule-linnovation-dans-le-commerce-en-france\/\">\u00e9tude<\/a> r\u00e9alis\u00e9e par KPMG et la Fevad analyse les comportements de la G\u00e9n\u00e9ration Z dans le secteur du e-commerce. Exigeante, connect\u00e9e et en qu\u00eate de transparence, cette g\u00e9n\u00e9ration oblige les marques \u00e0 innover\u00a0\u00e0 l\u2019image des \u201ccrew\u201d que YOP \u00e0 lanc\u00e9e ou encore en s\u2019appuyant sur des outils comme la gamification et la collaboration avec des influenceurs. Ces tendances, coupl\u00e9es \u00e0 une forte pr\u00e9sence sur des plateformes telles que TikTok, Instagram, Snapchat ou Discord, montrent comment les marques doivent adapter leurs strat\u00e9gies pour s\u00e9duire ce public exigeant.\u00a0<\/p>\n\n\n\n<p>Cependant, tout n\u2019est pas \u00e0 r\u00e9inventer. L\u2019article \u201c<a href=\"https:\/\/www.strategies.fr\/actualites\/agences\/LQ3759906C\/le-papier-un-outil-encore-strategique-pour-la-communication-institutionelle.html\">Le papier, un outil encore strat\u00e9gique pour la communication institutionnelle<\/a>\u201d, publi\u00e9 dans <em>Strat\u00e9gies<\/em>, rappelle que malgr\u00e9 la digitalisation, le papier reste pertinent. Positionn\u00e9 comme un support premium, il offre fiabilit\u00e9, \u00e9motion. St\u00e9phane Villey, directeur associ\u00e9 de l\u2019agence Entrecom, souligne que les outils traditionnels n\u2019ont pas compl\u00e8tement disparu, notamment dans les communications institutionnelles, o\u00f9 le papier renforce l\u2019image de s\u00e9rieux et d\u2019engagement.\u00a0<\/p>\n\n\n\n<p>Ainsi, pour rester pertinent, il est essentiel d\u2019innover en fonction de sa cible, en particulier avec les nouvelles g\u00e9n\u00e9rations comme la Gen Z, qui \u00e9voluent rapidement. Cela ne signifie pas abandonner les m\u00e9thodes traditionnelles, mais plut\u00f4t les r\u00e9inventer et les combiner avec les approches modernes. Par exemple, le papier peut \u00eatre revisit\u00e9 pour rester percutant et compl\u00e9mentaire aux outils num\u00e9riques. L\u2019enjeu est de s\u2019adapter \u00e0 chaque audience\u00a0des supports : le papier et le digital doivent coexister de mani\u00e8re compl\u00e9mentaire. Cette compl\u00e9mentarit\u00e9 ne repose pas sur la duplication des messages, mais sur leur adaptation au m\u00e9dia et \u00e0 la cible.\u00a0<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 14 novembre 2024, La R\u00e9clame a publi\u00e9 un article intitul\u00e9 \u201cComment Yop continue \u00e0 parler \u2018jeunes\u2019 \u00e0 50 ans ?\u201d. Cet article analyse la strat\u00e9gie de communication de YOP, marque embl\u00e9matique de yaourts \u00e0 boire, qui s\u2019efforce depuis cinq d\u00e9cennies de rester connect\u00e9e \u00e0 un public adolescent en perp\u00e9tuelle \u00e9volution. En misant notamment sur &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/2024\/11\/18\/rester-pertinent-face-a-ces-cibles-le-defi-des-marques-aujourdhui\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Rester pertinent face \u00e0 ces cibles : le d\u00e9fi des marques aujourd\u2019hui\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"predecessor-version":[{"id":34,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/33\/revisions\/34"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}