{"id":214,"date":"2024-12-30T11:22:07","date_gmt":"2024-12-30T10:22:07","guid":{"rendered":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/?p=214"},"modified":"2024-12-30T11:22:07","modified_gmt":"2024-12-30T10:22:07","slug":"limpact-de-la-surcharge-mediatique-comment-lutter-contre-la-fatigue-informationnelle","status":"publish","type":"post","link":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/2024\/12\/30\/limpact-de-la-surcharge-mediatique-comment-lutter-contre-la-fatigue-informationnelle\/","title":{"rendered":"L&rsquo;impact de la surcharge m\u00e9diatique : comment lutter contre la fatigue informationnelle"},"content":{"rendered":"\n<p>Le 11 d\u00e9cembre dernier, un article publi\u00e9 par <a href=\"https:\/\/www.cbnews.fr\/etudes\/image-54-francais-sont-fatigues-information-fondation-jean-jaures-obsoco-arte-89281\" data-type=\"link\" data-id=\"https:\/\/www.cbnews.fr\/etudes\/image-54-francais-sont-fatigues-information-fondation-jean-jaures-obsoco-arte-89281\">CB NEWS<\/a> mettait en lumi\u00e8re un ph\u00e9nom\u00e8ne pr\u00e9occupant : <strong>la fatigue informationnelle<\/strong>. L&rsquo;\u00e9tude men\u00e9e par la Fondation Jean-Jaur\u00e8s, L\u2019ObSoCo et Arte r\u00e9v\u00e8le un ph\u00e9nom\u00e8ne de \u00ab\u00a0grand exode informationnel\u00a0\u00bb parmi les Fran\u00e7ais, qui se sentent satur\u00e9s par un \u00e9cosyst\u00e8me m\u00e9diatique anxiog\u00e8ne et r\u00e9p\u00e9titif. Plus de la moiti\u00e9 des Fran\u00e7ais (54%) se disent fatigu\u00e9s de l&rsquo;information, et une grande majorit\u00e9 (80%) estime voir sans cesse les m\u00eames contenus. Une part importante \u00e9prouve des difficult\u00e9s \u00e0 distinguer la \u00ab\u00a0vraie\u00a0\u00bb information de la \u00ab\u00a0fausse\u00a0\u00bb et \u00e0 suivre l&rsquo;\u00e9volution des sujets. De plus, les Fran\u00e7ais deviennent de plus en plus imperm\u00e9ables \u00e0 l&rsquo;information, ne sachant plus ce qui est vrai ou faux, ce qui alimente un sentiment de d\u00e9couragement. Ce ph\u00e9nom\u00e8ne se traduit par une baisse de la diversit\u00e9 des canaux d&rsquo;information utilis\u00e9s, les m\u00e9dias traditionnels perdant du terrain au profit des r\u00e9seaux sociaux. Parall\u00e8lement, la confiance envers les m\u00e9dias reste partag\u00e9e, bien que la proportion de ceux n&rsquo;ayant \u00ab\u00a0pas du tout\u00a0\u00bb confiance ait augment\u00e9. Les Fran\u00e7ais semblent ainsi se replier sur les m\u00e9dias qu&rsquo;ils consid\u00e8rent comme fiables.\u00a0<\/p>\n\n\n\n<p>Ainsi, cet article m&rsquo;a pouss\u00e9 \u00e0 me poser des questions sur l&rsquo;impact de cette fatigue informationnelle et sur les moyens de lutter contre elle pour encourager les gens \u00e0 suivre l&rsquo;actualit\u00e9 de mani\u00e8re plus sereine.&nbsp;<\/p>\n\n\n\n<p>Premi\u00e8rement, l\u2019article <a href=\"https:\/\/www.la-croix.com\/a-vif\/l-acces-a-une-information-de-qualite-est-un-sujet-de-sante-publique-20240117\" data-type=\"link\" data-id=\"https:\/\/www.la-croix.com\/a-vif\/l-acces-a-une-information-de-qualite-est-un-sujet-de-sante-publique-20240117\">\u00ab L\u2019acc\u00e8s \u00e0 une information de qualit\u00e9 est un sujet de sant\u00e9 publique \u00bb<\/a> publi\u00e9 par La Croix confirme ce ph\u00e9nom\u00e8ne de fatigue informationnelle. D\u2019apr\u00e8s l\u2019OMS, cette fatigue est souvent accompagn\u00e9e de sympt\u00f4mes d\u00e9pressifs, d&rsquo;angoisse et de d\u00e9pendance. L&rsquo;exposition constante \u00e0 des informations anxiog\u00e8nes et souvent peu fiables engendre une confusion croissante, avec une difficult\u00e9 croissante \u00e0 distinguer le vrai du faux. Cette surcharge informationnelle contribue \u00e0 une fracture d\u00e9mocratique, alimentant le d\u00e9couragement et l\u2019abstention \u00e9lectorale.\u00a0\u00a0<\/p>\n\n\n\n<p>Par ailleurs, il est expliqu\u00e9 qu\u2019il est essentiel de renforcer l&rsquo;\u00e9ducation aux m\u00e9dias et l&rsquo;esprit critique d\u00e8s le plus jeune \u00e2ge, et de promouvoir des pratiques journalistiques de qualit\u00e9. Cela permettrait de restaurer la confiance dans les m\u00e9dias et de prot\u00e9ger la sant\u00e9 publique en mati\u00e8re d&rsquo;information.&nbsp;<\/p>\n\n\n\n<p>Par exemple, France info \u00e0 mis en place plusieurs strat\u00e9gies pour limiter la fatigue informationnelle qui sont expliqu\u00e9 dans un article du <a href=\"https:\/\/www.lemonde.fr\/economie\/article\/2024\/06\/28\/franceinfo-veut-lutter-contre-la-fatigue-informationnelle-a-la-rentree_6245032_3234.html\" data-type=\"link\" data-id=\"https:\/\/www.lemonde.fr\/economie\/article\/2024\/06\/28\/franceinfo-veut-lutter-contre-la-fatigue-informationnelle-a-la-rentree_6245032_3234.html\">Monde<\/a>. Jean-Philippe Baille, directeur de la cha\u00eene, a annonc\u00e9 un renforcement de l\u2019interactivit\u00e9 avec les auditeurs pour mieux expliquer les coulisses de l\u2019information. Le programme \u00ab\u00a012-15\u00a0\u00bb sera ainsi r\u00e9organis\u00e9 pour permettre aux journalistes de d\u00e9tailler les choix \u00e9ditoriaux, en clarifiant notamment des sujets sensibles, comme la couverture de zones de guerre. De plus, les rappels de l&rsquo;actualit\u00e9 seront espac\u00e9s, passant de quatre \u00e0 deux par heure, afin d\u2019a\u00e9rer l\u2019antenne et de r\u00e9duire la sensation de surcharge informationnelle. Ces changements visent \u00e0 donner plus de clart\u00e9 et de transparence, tout en \u00e9vitant le matraquage constant des informations.\u00a0<\/p>\n\n\n\n<p>Dans ce contexte de saturation informationnelle, les professionnels de la communication doivent \u00eatre particuli\u00e8rement attentifs \u00e0 la mani\u00e8re dont ils transmettent les informations. Il est crucial de choisir avec soin les messages \u00e0 diffuser, en \u00e9vitant d\u2019en faire trop. Trop d&rsquo;informations, livr\u00e9es de mani\u00e8re excessive ou redondante, risquent de perdre l&rsquo;attention du public et de cr\u00e9er une forme de d\u00e9sengagement. Les communicants doivent donc opter pour une approche mesur\u00e9e, en privil\u00e9giant la clart\u00e9 et la pertinence des contenus afin de maintenir l&rsquo;int\u00e9r\u00eat de leurs cibles sans les submerger. Une communication bien dos\u00e9e permet de pr\u00e9server l&rsquo;impact des messages et d&rsquo;\u00e9viter que ceux-ci ne soient noy\u00e9s dans l&rsquo;oc\u00e9an d&rsquo;informations quotidiennes.&nbsp;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 11 d\u00e9cembre dernier, un article publi\u00e9 par CB NEWS mettait en lumi\u00e8re un ph\u00e9nom\u00e8ne pr\u00e9occupant : la fatigue informationnelle. L&rsquo;\u00e9tude men\u00e9e par la Fondation Jean-Jaur\u00e8s, L\u2019ObSoCo et Arte r\u00e9v\u00e8le un ph\u00e9nom\u00e8ne de \u00ab\u00a0grand exode informationnel\u00a0\u00bb parmi les Fran\u00e7ais, qui se sentent satur\u00e9s par un \u00e9cosyst\u00e8me m\u00e9diatique anxiog\u00e8ne et r\u00e9p\u00e9titif. Plus de la moiti\u00e9 des &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/2024\/12\/30\/limpact-de-la-surcharge-mediatique-comment-lutter-contre-la-fatigue-informationnelle\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0L&rsquo;impact de la surcharge m\u00e9diatique : comment lutter contre la fatigue informationnelle\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":1,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":215,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/posts\/214\/revisions\/215"}],"wp:attachment":[{"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webcom.iutlan.univ-rennes1.fr\/abenatre\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}